{"id":10791,"date":"2020-10-30T10:42:02","date_gmt":"2020-10-30T13:42:02","guid":{"rendered":"http:\/\/www.mpc.pr.gov.br\/?p=10791"},"modified":"2020-11-19T15:10:26","modified_gmt":"2020-11-19T18:10:26","slug":"concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica","status":"publish","type":"post","link":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/","title":{"rendered":"Concess\u00e3o de vantagem aos servidores deve ser autorizada por norma legal espec\u00edfica"},"content":{"rendered":"<figure id=\"attachment_9243\" aria-describedby=\"caption-attachment-9243\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-9243 size-full\" src=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg\" alt=\"\" width=\"300\" height=\"236\" \/><figcaption id=\"caption-attachment-9243\" class=\"wp-caption-text\">O artigo 169, \u00a71\u00ba, da Constitui\u00e7\u00e3o Federal estabelece os crit\u00e9rios para concess\u00e3o de vantagens aos servidores. Ilustra\u00e7\u00e3o: DCS-TCEPR.<\/figcaption><\/figure>\n<p>O Pleno do Tribunal de Contas do Paran\u00e1 (TCE-PR) encaminhou recomenda\u00e7\u00e3o ao munic\u00edpio de Conselheiro Mairinck para que se abstenha da pr\u00e1tica de concess\u00e3o de vantagem aos servidores municipais, sem autoriza\u00e7\u00e3o legislativa. A decis\u00e3o foi tomada em um processo de Representa\u00e7\u00e3o da <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l8666cons.htm\">Lei n\u00b0 8.666\/93<\/a>, o qual noticiava supostas irregularidades no Preg\u00e3o Presencial n\u00ba 41\/2019, destinado a compra de 270 unidades de panetones trufados, no valor total de R$ 4.584,60, para serem distribu\u00eddos aos funcion\u00e1rios p\u00fablicos da entidade nas festividades natalinas de 2019.<\/p>\n<p>A Representa\u00e7\u00e3o da Lei de Licita\u00e7\u00f5es foi proposta pela Procuradora da C\u00e2mara de Vereadores do munic\u00edpio, que alegou que cada unidade de panetone custou o valor de R$ 16,98, sendo que em pesquisa de mercado realizada pela Representante, o mesmo produto (marca, peso e sabor), no dia 18 de dezembro de 2019, correspondia aos valores de R$ 12,59, R$ 12,99 e o mais caro, R$ 14,95.<\/p>\n<p>Neste sentido, a Procuradora aponta que o Poder Executivo municipal teria pago nos itens valores acima dos pre\u00e7os praticados no mercado, totalizando um sobrepre\u00e7o de R$ 2.192,50. Al\u00e9m disso, a Representante tamb\u00e9m destacou que em 2018 o munic\u00edpio realizou o Preg\u00e3o Presencial n\u00ba 54\/2018, destinado a aquisi\u00e7\u00e3o do mesmo objeto, no valor total de R$ 4.344,20, sendo que cada unidade custou R$ 14,98. Ambos os contratos, de 2018 e 2019, foram adjudicados em favor da empresa VCB MAICHAKI ME.<\/p>\n<p><strong>Instru\u00e7\u00e3o do Processo<\/strong><\/p>\n<p>A Coordenadoria de Gest\u00e3o Municipal (CGM) aponta que n\u00e3o se verifica ocorr\u00eancia de ofensa ao princ\u00edpio da economicidade, por poss\u00edvel sobrepre\u00e7o na aquisi\u00e7\u00e3o dos produtos, ou mesmo de ofensa ao princ\u00edpio da impessoalidade, pois os itens foram destinados a todos os servidores p\u00fablicos municipais. Contudo, observa que a irregularidade se configura em raz\u00e3o de v\u00edcio na sua origem, uma vez que o fornecimento de panetones para festa natalina ou quaisquer vantagens similares para os servidores municipais deve ser autorizada por norma legal espec\u00edfica, a qual n\u00e3o h\u00e1 no munic\u00edpio.<\/p>\n<p>A unidade t\u00e9cnica se manifestou conclusivamente pela proced\u00eancia da Representa\u00e7\u00e3o e aplica\u00e7\u00e3o da multa constante do artigo 87, IV, \u201cg\u201d da <a href=\"https:\/\/www1.tce.pr.gov.br\/multimidia\/2005\/12\/pdf\/00084503.pdf\">LC n\u00ba 113\/2005<\/a> ao Prefeito Municipal \u00e0 \u00e9poca, Alex Sandro Pereira Costa Domingues.<\/p>\n<p>J\u00e1 o MP de Contas do Paran\u00e1 (MPC-PR), por meio do <a href=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/10\/Parecer-526-20.pdf\">Parecer n\u00ba 562\/20<\/a>, opinou pela reatua\u00e7\u00e3o do processo como Den\u00fancia, e delibera\u00e7\u00e3o sobre a possibilidade de aplica\u00e7\u00e3o das disposi\u00e7\u00f5es da <a href=\"https:\/\/www1.tce.pr.gov.br\/conteudo\/resolucao-n-60-de-17-de-fevereiro-de-2017\/298351\/area\/10\">Resolu\u00e7\u00e3o n\u00ba 60\/2017<\/a>, com o consequente encerramento do processamento, em raz\u00e3o da quantifica\u00e7\u00e3o de dano em valor inferior ao limite de al\u00e7ada fixado na citada normativa.<\/p>\n<p>Em caso de entendimento diverso do relator, o MPC-PR opina pela cita\u00e7\u00e3o dos agentes que participaram da fase interna do procedimento licitat\u00f3rio, com emiss\u00e3o de determina\u00e7\u00e3o \u00e0 CGM para que leve em considera\u00e7\u00e3o tais gastos na apura\u00e7\u00e3o do \u00edndice de despesas com pessoal, quando da an\u00e1lise de presta\u00e7\u00e3o de contas do Prefeito de Conselheiro Mairinck, do exerc\u00edcio de 2019.<\/p>\n<p><strong>Decis\u00e3o<\/strong><\/p>\n<p>O relator do processo, Conselheiro Artag\u00e3o de Mattos Le\u00e3o, se manifestou pela proced\u00eancia da Representa\u00e7\u00e3o, em raz\u00e3o da concess\u00e3o de vantagem aos servidores municipais, sem previs\u00e3o legal autorizativa, conforme estabelece a <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/constituicao.htm\">Constitui\u00e7\u00e3o Federal<\/a>, em seu artigo 169, \u00a71\u00ba.<\/p>\n<p>Contudo, o relator rejeito as propostas do MP de Contas, por entender que a reatua\u00e7\u00e3o do processo neste momento n\u00e3o se faz oportuna. Da mesma forma, o relator deixou de acolher o opinativo ministerial quanto ao encerramento dos autos, considerando a <a href=\"https:\/\/www1.tce.pr.gov.br\/conteudo\/resolucao-n-60-de-17-de-fevereiro-de-2017\/298351\/area\/10\">Resolu\u00e7\u00e3o n\u00ba 60\/2017<\/a>, em raz\u00e3o da necessidade de a Corte refrear futuras aquisi\u00e7\u00f5es com objeto similar.<\/p>\n<p>Destacou que, apesar do baixo valor despendido e da aus\u00eancia de ofensa aos princ\u00edpios da economicidade e impessoalidade, conforme apontado pela CGM, verificou-se que n\u00e3o h\u00e1 lei municipal prevendo tal benef\u00edcio, configurando-se ofensa ao princ\u00edpio da legalidade.<\/p>\n<p>Neste sentido, conforme entendimento do TCE-PR em recentes decis\u00f5es do Tribunal Pleno (Ac\u00f3rd\u00e3os n\u00b0 1206\/192 e n\u00b0 1472\/203 ), a concess\u00e3o de vantagem aos servidores p\u00fablicos deve ser precedia da pr\u00e9via dota\u00e7\u00e3o or\u00e7ament\u00e1ria, autoriza\u00e7\u00e3o espec\u00edfica na lei de diretrizes or\u00e7ament\u00e1rias, somados aos requisitos da<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/lcp\/lcp101.htm\"> Lei Complementar n\u00ba 101\/00<\/a>.<\/p>\n<p>Em sua decis\u00e3o, o relator deixou de aplicar qualquer multa aos gestores, pois trata-se de um procedimento licitat\u00f3rio de pequena monta, somado ao fato de n\u00e3o constar dos autos prova de dolo ou ma-f\u00e9 dos agentes envolvidos. Entretanto, como forma de refrear essa pr\u00e1tica, o relator expediu uma recomenda\u00e7\u00e3o ao munic\u00edpio, para que se abstenha da pr\u00e1tica de concess\u00e3o de vantagem aos servidores municipais, sem autoriza\u00e7\u00e3o legislativa.<\/p>\n<p>Os membros do Tribunal Pleno acompanharam, por unanimidade, o voto do relator, durante a Sess\u00e3o Virtual n\u00b0 28, de 16 de setembro de 2020. A \u00edntegra da decis\u00e3o est\u00e1 dispon\u00edvel no <a href=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/10\/Acordao-2500-20.pdf\">Ac\u00f3rd\u00e3o n\u00b0 2500\/20<\/a>.<\/p>\n<blockquote><p><span style=\"color: #820007;\"><strong><u>Informa\u00e7\u00e3o para consulta processual<\/u><\/strong><\/span><\/p>\n<table border=\"0\" width=\"581\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td><strong>Processo n\u00ba<\/strong>:<\/td>\n<td>173180\/20<\/td>\n<\/tr>\n<tr>\n<td><strong>Ac\u00f3rd\u00e3o n\u00ba<\/strong>:<\/td>\n<td>2500\/20 \u2013 Tribunal Pleno<\/td>\n<\/tr>\n<tr>\n<td><strong>Assunto<\/strong>:<\/td>\n<td>Representa\u00e7\u00e3o da Lei n\u00ba 8.666\/1993<\/td>\n<\/tr>\n<tr>\n<td><strong>Entidade<\/strong>:<\/td>\n<td>Munic\u00edpio de Conselheiro Mairick<\/td>\n<\/tr>\n<tr>\n<td><strong>Interessados<\/strong>:<\/td>\n<td>Alex Sandro Pereira Costa Domingues, Andreia Vivian Amaral Valentini, Munic\u00edpio de Conselheiro Mairinck<\/td>\n<\/tr>\n<tr>\n<td><strong>Relator<\/strong>:<\/td>\n<td>Conselheiro Jose Durval Mattos do Amaral<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>O Pleno do Tribunal de Contas do Paran\u00e1 (TCE-PR) encaminhou recomenda\u00e7\u00e3o ao munic\u00edpio de Conselheiro Mairinck para que se abstenha da pr\u00e1tica de concess\u00e3o de vantagem aos servidores municipais, sem autoriza\u00e7\u00e3o legislativa. A decis\u00e3o foi tomada em um processo de Representa\u00e7\u00e3o da Lei n\u00b0 8.666\/93, o qual noticiava supostas irregularidades no Preg\u00e3o Presencial n\u00ba 41\/2019, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9243,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[145,13,135,144,39,71,143],"class_list":["post-10791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-todas-as-noticias","tag-conselheiro-mairinck","tag-mpc-pr","tag-representacao-da-lei-n-8-666-93","tag-servidor-publico","tag-tce-pr","tag-tribunal-pleno","tag-vantagens","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concess\u00e3o de vantagem aos servidores deve ser autorizada por norma legal espec\u00edfica - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1<\/title>\n<meta name=\"description\" content=\"O TCE-PR encaminhou recomenda\u00e7\u00e3o ao munic\u00edpio de Conselheiro Mairinck para que se abstenha da pr\u00e1tica de concess\u00e3o de vantagem aos servidores municipais, sem autoriza\u00e7\u00e3o legislativa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concess\u00e3o de vantagem aos servidores deve ser autorizada por norma legal espec\u00edfica - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"og:description\" content=\"O TCE-PR encaminhou recomenda\u00e7\u00e3o ao munic\u00edpio de Conselheiro Mairinck para que se abstenha da pr\u00e1tica de concess\u00e3o de vantagem aos servidores municipais, sem autoriza\u00e7\u00e3o legislativa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/\" \/>\n<meta property=\"og:site_name\" content=\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mpc.pr\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-30T13:42:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-19T18:10:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"236\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mpcontaspr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mpcontaspr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/\"},\"author\":{\"name\":\"mpcontaspr\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/person\\\/2d83cb8980538d0ec174e8a6284f5e11\"},\"headline\":\"Concess\u00e3o de vantagem aos servidores deve ser autorizada por norma legal espec\u00edfica\",\"datePublished\":\"2020-10-30T13:42:02+00:00\",\"dateModified\":\"2020-11-19T18:10:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/\"},\"wordCount\":909,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/FISCALIZAR-01.jpg\",\"keywords\":[\"Conselheiro Mairinck\",\"MPC-PR\",\"Representa\u00e7\u00e3o da Lei n\u00b0 8.666\\\/93\",\"Servidor P\u00fablico\",\"TCE-PR\",\"Tribunal Pleno\",\"Vantagens\"],\"articleSection\":[\"Todas as not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/\",\"name\":\"Concess\u00e3o de vantagem aos servidores deve ser autorizada por norma legal espec\u00edfica - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/FISCALIZAR-01.jpg\",\"datePublished\":\"2020-10-30T13:42:02+00:00\",\"dateModified\":\"2020-11-19T18:10:26+00:00\",\"description\":\"O TCE-PR encaminhou recomenda\u00e7\u00e3o ao munic\u00edpio de Conselheiro Mairinck para que se abstenha da pr\u00e1tica de concess\u00e3o de vantagem aos servidores municipais, sem autoriza\u00e7\u00e3o legislativa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/FISCALIZAR-01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/FISCALIZAR-01.jpg\",\"width\":300,\"height\":236,\"caption\":\"Fiscalizar os gastos com pessoal, principal item de despesa dos \u00f3rg\u00e3os p\u00fablicos, \u00e9 atribui\u00e7\u00e3o do TCE-PR. Ilustra\u00e7\u00e3o: N\u00facleo de Imagem\\\/Diretoria de Comunica\u00e7\u00e3o Social.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concess\u00e3o de vantagem aos servidores deve ser autorizada por norma legal espec\u00edfica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"contentUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"width\":243,\"height\":73,\"caption\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mpc.pr\",\"https:\\\/\\\/www.instagram.com\\\/mpc.pr\\\/?hl=pt-br\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHri5oEM8DV0ztX57E0sBSw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/person\\\/2d83cb8980538d0ec174e8a6284f5e11\",\"name\":\"mpcontaspr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g\",\"caption\":\"mpcontaspr\"},\"sameAs\":[\"http:\\\/\\\/www.mpc.pr.gov.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concess\u00e3o de vantagem aos servidores deve ser autorizada por norma legal espec\u00edfica - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","description":"O TCE-PR encaminhou recomenda\u00e7\u00e3o ao munic\u00edpio de Conselheiro Mairinck para que se abstenha da pr\u00e1tica de concess\u00e3o de vantagem aos servidores municipais, sem autoriza\u00e7\u00e3o legislativa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/","og_locale":"pt_BR","og_type":"article","og_title":"Concess\u00e3o de vantagem aos servidores deve ser autorizada por norma legal espec\u00edfica - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","og_description":"O TCE-PR encaminhou recomenda\u00e7\u00e3o ao munic\u00edpio de Conselheiro Mairinck para que se abstenha da pr\u00e1tica de concess\u00e3o de vantagem aos servidores municipais, sem autoriza\u00e7\u00e3o legislativa.","og_url":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/","og_site_name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","article_publisher":"https:\/\/www.facebook.com\/mpc.pr","article_published_time":"2020-10-30T13:42:02+00:00","article_modified_time":"2020-11-19T18:10:26+00:00","og_image":[{"width":300,"height":236,"url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg","type":"image\/jpeg"}],"author":"mpcontaspr","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mpcontaspr","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/#article","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/"},"author":{"name":"mpcontaspr","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/person\/2d83cb8980538d0ec174e8a6284f5e11"},"headline":"Concess\u00e3o de vantagem aos servidores deve ser autorizada por norma legal espec\u00edfica","datePublished":"2020-10-30T13:42:02+00:00","dateModified":"2020-11-19T18:10:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/"},"wordCount":909,"commentCount":0,"publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg","keywords":["Conselheiro Mairinck","MPC-PR","Representa\u00e7\u00e3o da Lei n\u00b0 8.666\/93","Servidor P\u00fablico","TCE-PR","Tribunal Pleno","Vantagens"],"articleSection":["Todas as not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/","url":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/","name":"Concess\u00e3o de vantagem aos servidores deve ser autorizada por norma legal espec\u00edfica - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/#primaryimage"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg","datePublished":"2020-10-30T13:42:02+00:00","dateModified":"2020-11-19T18:10:26+00:00","description":"O TCE-PR encaminhou recomenda\u00e7\u00e3o ao munic\u00edpio de Conselheiro Mairinck para que se abstenha da pr\u00e1tica de concess\u00e3o de vantagem aos servidores municipais, sem autoriza\u00e7\u00e3o legislativa.","breadcrumb":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/#primaryimage","url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg","contentUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg","width":300,"height":236,"caption":"Fiscalizar os gastos com pessoal, principal item de despesa dos \u00f3rg\u00e3os p\u00fablicos, \u00e9 atribui\u00e7\u00e3o do TCE-PR. Ilustra\u00e7\u00e3o: N\u00facleo de Imagem\/Diretoria de Comunica\u00e7\u00e3o Social."},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/concessao-de-vantagem-aos-servidores-deve-ser-autorizada-por-norma-legal-especifica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.mpc.pr.gov.br\/"},{"@type":"ListItem","position":2,"name":"Concess\u00e3o de vantagem aos servidores deve ser autorizada por norma legal espec\u00edfica"}]},{"@type":"WebSite","@id":"https:\/\/www.mpc.pr.gov.br\/#website","url":"https:\/\/www.mpc.pr.gov.br\/","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","description":"","publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpc.pr.gov.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.mpc.pr.gov.br\/#organization","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","url":"https:\/\/www.mpc.pr.gov.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","contentUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","width":243,"height":73,"caption":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mpc.pr","https:\/\/www.instagram.com\/mpc.pr\/?hl=pt-br","https:\/\/www.youtube.com\/channel\/UCHri5oEM8DV0ztX57E0sBSw"]},{"@type":"Person","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/person\/2d83cb8980538d0ec174e8a6284f5e11","name":"mpcontaspr","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g","caption":"mpcontaspr"},"sameAs":["http:\/\/www.mpc.pr.gov.br"]}]}},"rttpg_featured_image_url":{"full":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg",300,236,false],"landscape":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg",300,236,false],"portraits":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg",300,236,false],"thumbnail":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01-150x150.jpg",150,150,true],"medium":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg",300,236,false],"large":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg",300,236,false],"1536x1536":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg",300,236,false],"2048x2048":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg",300,236,false],"ocean-thumb-m":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg",300,236,false],"ocean-thumb-ml":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg",300,236,false],"ocean-thumb-l":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/04\/FISCALIZAR-01.jpg",300,236,false]},"rttpg_author":{"display_name":"mpcontaspr","author_link":"https:\/\/www.mpc.pr.gov.br\/index.php\/author\/mpcontaspr\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/category\/todas-as-noticias\/\" rel=\"category tag\">Todas as not\u00edcias<\/a>","rttpg_excerpt":"O Pleno do Tribunal de Contas do Paran\u00e1 (TCE-PR) encaminhou recomenda\u00e7\u00e3o ao munic\u00edpio de Conselheiro Mairinck para que se abstenha da pr\u00e1tica de concess\u00e3o de vantagem aos servidores municipais, sem autoriza\u00e7\u00e3o legislativa. A decis\u00e3o foi tomada em um processo de Representa\u00e7\u00e3o da Lei n\u00b0 8.666\/93, o qual noticiava supostas irregularidades no Preg\u00e3o Presencial n\u00ba 41\/2019,&hellip;","_links":{"self":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/10791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=10791"}],"version-history":[{"count":3,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/10791\/revisions"}],"predecessor-version":[{"id":10797,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/10791\/revisions\/10797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media\/9243"}],"wp:attachment":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=10791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/categories?post=10791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/tags?post=10791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}