{"id":11569,"date":"2021-03-10T13:07:23","date_gmt":"2021-03-10T16:07:23","guid":{"rendered":"http:\/\/www.mpc.pr.gov.br\/?p=11569"},"modified":"2021-03-24T13:45:23","modified_gmt":"2021-03-24T16:45:23","slug":"tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente","status":"publish","type":"post","link":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/","title":{"rendered":"TCE-PR determina que ParanaPrevid\u00eancia adote medidas para ressarcir valores pagos indevidamente"},"content":{"rendered":"<figure id=\"attachment_11566\" aria-describedby=\"caption-attachment-11566\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-11566\" src=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia-300x234.jpg\" alt=\"\" width=\"300\" height=\"234\" srcset=\"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia-300x234.jpg 300w, https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-11566\" class=\"wp-caption-text\">Sede do servi\u00e7o social aut\u00f4nomo Paranaprevid\u00eancia, em Curitiba. Foto: Wagner Ara\u00fajo\/Divulga\u00e7\u00e3o TCE-PR.<\/figcaption><\/figure>\n<p>Acompanhando o opinativo do MP de Contas do Paran\u00e1 (MPC-PR), a Primeira C\u00e2mara do Tribunal de Contas do Paran\u00e1 (TCE-PR) expediu determina\u00e7\u00e3o \u00e0 ParanaPrevid\u00eancia para que, no prazo de 30 dias, adote medidas para o ressarcimento de valores indevidamente pagos a maior para servidora aposentada no cargo de Professora do Ensino Superior.<\/p>\n<p>Tal decis\u00e3o foi proferida no <a href=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/Acordao-408-21.pdf\">Ac\u00f3rd\u00e3o n\u00ba 408\/21<\/a>, que negou o registro do ato de revis\u00e3o de proventos da servidora, originalmente aposentada com fundamento no art. 3\u00ba da EC n\u00ba 47\/2005, com benef\u00edcio no valor de R$ 10.961,18, conforme Resolu\u00e7\u00e3o 12617\/2018. O ato revisional, formalizado posteriormente pela Resolu\u00e7\u00e3o n\u00ba 84\/2019, teve por finalidade incorporar a verba de Tempo Integral de Registro do Ato (TIDE) de forma integral ao c\u00e1lculo dos proventos, o que elevou o benef\u00edcio para o valor de R$ 14.977,17.<\/p>\n<p><strong>Instru\u00e7\u00e3o do processo<\/strong><\/p>\n<p>Ap\u00f3s analisar o processo, a Coordenadoria de Gest\u00e3o Estadual (CGE) apontou que, conforme a Uniformiza\u00e7\u00e3o de Jurisprud\u00eancia n\u00ba 21 objeto dos autos n\u00ba 806898\/15, o TCE-PR definiu que a parcela TIDE, uma vez paga, integra o regime de trabalho dos professores de ensino superior, devendo ser incorporada aos proventos de inativa\u00e7\u00e3o pelo recebido pelo servidor enquanto ativo, desde que sobre tal parcela tenha havido contribui\u00e7\u00e3o previdenci\u00e1ria durante 15 anos, conforme art. 5\u00ba, caput, da <a href=\"https:\/\/www.legislacao.pr.gov.br\/legislacao\/exibirAto.do?action=iniciarProcesso&amp;codAto=205125&amp;codItemAto=1278047#1278047\">Lei Estadual n\u00ba 19.594\/18<\/a>.<\/p>\n<p>Contudo, verificou-se que a servidora recebeu a parcela TIDE de setembro de 2010 a novembro de 2017, totalizando pouco mais de 7 anos de contribui\u00e7\u00e3o, per\u00edodo inferior ao previsto na citada legisla\u00e7\u00e3o. Em raz\u00e3o disso, a unidade t\u00e9cnica se manifestou conclusivamente pela negativa do ato revisional.<\/p>\n<p>O MP de Contas, mediante o <a href=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/Parecer-41-21.pdf\">Parecer n\u00ba 41\/21<\/a>, observou que a ParanaPrevid\u00eancia efetuou a revis\u00e3o dos proventos em atendimento \u00e0 decis\u00e3o liminar proferida em junho de 2018 pelo \u00d3rg\u00e3o Especial do Tribunal de Justi\u00e7a, nos autos de Agravo Interno C\u00edvel n\u00ba 1.746.013-8\/013. No entanto, em posterior Agravo Interno interposto pelo Estado do Paran\u00e1 (autos n\u00ba 1.746.013- 8\/03), o \u00d3rg\u00e3o Especial do Tribunal de Justi\u00e7a decidiu, em abril de 2019, cassar a liminar anteriormente concedida.<\/p>\n<p>Dessa forma, cabia a entidade previdenci\u00e1ria, a partir do conhecimento da cassa\u00e7\u00e3o da liminar, cessar os pagamentos decorrentes do ato revisional, adequando os proventos da servidora e revogar a Resolu\u00e7\u00e3o n\u00ba 84\/2019. Todavia, em consulta ao portal da transpar\u00eancia do Governo do Estado, o MPC-PR verificou que mesmo ap\u00f3s a cassa\u00e7\u00e3o da liminar, os proventos continuaram a ser pagos conforme os valores fixados no ato revisional, ao longo de todo o exerc\u00edcio de 2020.<\/p>\n<p>Diante de tais fatos, o MP de Contas acompanhou o opinativo da CGM pela negativa de registro do ato de revis\u00e3o de proventos, acrescida da fixa\u00e7\u00e3o do prazo de 30 dias para que a ParanaPrevid\u00eancia demonstre o retorno do benef\u00edcio aos valores fixados na original Resolu\u00e7\u00e3o n\u00ba 12.617\/2018. Sugeriu, ainda, a emiss\u00e3o de determina\u00e7\u00e3o com vistas ao ressarcimento dos valores indevidamente pagos a maior, sob pena de instaura\u00e7\u00e3o de Tomada de Contas Extraordin\u00e1ria.<\/p>\n<p><strong>Decis\u00e3o<\/strong><\/p>\n<p>O relator do processo, Conselheiro Ivan Lelis Bonilha, acompanhou as manifesta\u00e7\u00f5es uniformes do \u00f3rg\u00e3o ministerial e da unidade t\u00e9cnica no sentido da negativa de registro do ato de revis\u00e3o de proventos em apre\u00e7o, e acolheu a proposta do MPC-PR quanto \u00e0 expedi\u00e7\u00e3o de determina\u00e7\u00e3o \u00e0 ParanaPrevid\u00eancia para que, no prazo de 30 dias, demonstre o retorno do benef\u00edcio aos valores fixados na Resolu\u00e7\u00e3o n\u00ba 12.617\/2018 e adote provid\u00eancias com vistas ao ressarcimento dos valores indevidamente pagos a maior, ap\u00f3s a cassa\u00e7\u00e3o da liminar mencionada.<\/p>\n<p>Os membros da Primeira C\u00e2mara acompanharam, por unanimidade, o voto do relator durante a sess\u00e3o virtual n\u00ba 2 de 25 de fevereiro de 2021.<\/p>\n<p>A integra da decis\u00e3o, proferida no Ac\u00f3rd\u00e3o n\u00b0 408\/21, est\u00e1 dispon\u00edvel <a href=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/Acordao-408-21.pdf\">aqui<\/a>.<\/p>\n<div class=\"\" data-block=\"true\" data-editor=\"855pq\" data-offset-key=\"eohim-0-0\">\n<blockquote><p><span style=\"color: #820007;\"><strong><u>Informa\u00e7\u00e3o para consulta processual<\/u><\/strong><\/span><\/p>\n<table border=\"0\" width=\"572\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td><strong>Processo<\/strong>\u00a0<strong>n\u00ba<\/strong>:<\/td>\n<td>819935\/19<\/td>\n<\/tr>\n<tr>\n<td><strong>Ac\u00f3rd\u00e3o n\u00ba:<\/strong><\/td>\n<td>408\/21 &#8211; Primeira C\u00e2mara<\/td>\n<\/tr>\n<tr>\n<td><strong>Assunto<\/strong>:<\/td>\n<td>Revis\u00e3o de Proventos<\/td>\n<\/tr>\n<tr>\n<td><strong>Entidade<\/strong>:<\/td>\n<td>ParanaPrevid\u00eancia<\/td>\n<\/tr>\n<tr>\n<td><strong>Interessados<\/strong>:<\/td>\n<td>Felipe Jose Vidigal dos Santos, Marlus de Oliveira, Reinhold Stephanes, Ricardina Dias<\/td>\n<\/tr>\n<tr>\n<td><b>Advogado \/ Procurador:<\/b><\/td>\n<td>Ana Paula Kucaniz, Andrea Cristine Arcego, Andreia Brizola de Oliveira Furini, Anna Paula do Rocio Oya dos Santos, Caroline Fantin Marsaro, Claudinei Martins Gonzaga, Daniela dos Santos Tavares, Douglas Murilo dos Reis, Fabiano Jorge Stainzack, Heloyse Contador Rocha Maziero Jakiemiv, Isabelle Gion\u00e9dis Gulin, Isac Teixeira de Lima, Iuri Ferrari Cocicov, Jacson Luiz Pinto, Janaina de Assis, Jo\u00e3o Paulo Opuszka Machado, Jose Manuel Justo Silva, Juarez Pereira de Souza, Luciana de Oliveira Felix Borges, Luciano Lorusso Miranda, Maria Alice Tornesi Sosinski, Michele Correa, Ozilda da Silva Costa, Patricia Kavetski Sabadin, Patr\u00edcia Rodrigues Caffarate, Priscila Cristiane Jaworski, Rafael Augusto Cassou, Rafael Forneck Bahiense Gomes, Rita de Cassia Ribas Taques, Sheila Foga\u00e7a de Souza, Wellington Neves Salmazo<\/td>\n<\/tr>\n<tr>\n<td><strong>Relator<\/strong>:<\/td>\n<td>Conselheiro Ivan Lelis Bonilha<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/blockquote>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Acompanhando o opinativo do MP de Contas do Paran\u00e1 (MPC-PR), a Primeira C\u00e2mara do Tribunal de Contas do Paran\u00e1 (TCE-PR) expediu determina\u00e7\u00e3o \u00e0 ParanaPrevid\u00eancia para que, no prazo de 30 dias, adote medidas para o ressarcimento de valores indevidamente pagos a maior para servidora aposentada no cargo de Professora do Ensino Superior. Tal decis\u00e3o foi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[29,187,217,13,213,149,216,214,39,215],"class_list":["post-11569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-todas-as-noticias","tag-aposentadoria","tag-beneficio","tag-ensino-superior","tag-mpc-pr","tag-paranaprevidencia","tag-primeira-camara","tag-professora","tag-revisao-de-proventos","tag-tce-pr","tag-uniformidade-de-jurisprudencia","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TCE-PR determina que ParanaPrevid\u00eancia adote medidas para ressarcir valores pagos indevidamente - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TCE-PR determina que ParanaPrevid\u00eancia adote medidas para ressarcir valores pagos indevidamente - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"og:description\" content=\"Acompanhando o opinativo do MP de Contas do Paran\u00e1 (MPC-PR), a Primeira C\u00e2mara do Tribunal de Contas do Paran\u00e1 (TCE-PR) expediu determina\u00e7\u00e3o \u00e0 ParanaPrevid\u00eancia para que, no prazo de 30 dias, adote medidas para o ressarcimento de valores indevidamente pagos a maior para servidora aposentada no cargo de Professora do Ensino Superior. Tal decis\u00e3o foi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/\" \/>\n<meta property=\"og:site_name\" content=\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mpc.pr\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-10T16:07:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-24T16:45:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mpcontaspr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mpcontaspr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/\"},\"author\":{\"name\":\"mpcontaspr\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/person\\\/2d83cb8980538d0ec174e8a6284f5e11\"},\"headline\":\"TCE-PR determina que ParanaPrevid\u00eancia adote medidas para ressarcir valores pagos indevidamente\",\"datePublished\":\"2021-03-10T16:07:23+00:00\",\"dateModified\":\"2021-03-24T16:45:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/\"},\"wordCount\":837,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ParanaPrevidencia.jpg\",\"keywords\":[\"Aposentadoria\",\"Benef\u00edcio\",\"Ensino Superior\",\"MPC-PR\",\"ParanaPrevid\u00eancia\",\"Primeira C\u00e2mara\",\"Professora\",\"Revis\u00e3o de Proventos\",\"TCE-PR\",\"Uniformidade de Jurisprud\u00eancia\"],\"articleSection\":[\"Todas as not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/\",\"name\":\"TCE-PR determina que ParanaPrevid\u00eancia adote medidas para ressarcir valores pagos indevidamente - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ParanaPrevidencia.jpg\",\"datePublished\":\"2021-03-10T16:07:23+00:00\",\"dateModified\":\"2021-03-24T16:45:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ParanaPrevidencia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ParanaPrevidencia.jpg\",\"width\":640,\"height\":500,\"caption\":\"Sede do servi\u00e7o social aut\u00f4nomo Paranaprevid\u00eancia, em Curitiba. Foto: Wagner Ara\u00fajo\\\/Divulga\u00e7\u00e3o TCE-PR.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TCE-PR determina que ParanaPrevid\u00eancia adote medidas para ressarcir valores pagos indevidamente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"contentUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"width\":243,\"height\":73,\"caption\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mpc.pr\",\"https:\\\/\\\/www.instagram.com\\\/mpc.pr\\\/?hl=pt-br\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHri5oEM8DV0ztX57E0sBSw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/person\\\/2d83cb8980538d0ec174e8a6284f5e11\",\"name\":\"mpcontaspr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g\",\"caption\":\"mpcontaspr\"},\"sameAs\":[\"http:\\\/\\\/www.mpc.pr.gov.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TCE-PR determina que ParanaPrevid\u00eancia adote medidas para ressarcir valores pagos indevidamente - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/","og_locale":"pt_BR","og_type":"article","og_title":"TCE-PR determina que ParanaPrevid\u00eancia adote medidas para ressarcir valores pagos indevidamente - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","og_description":"Acompanhando o opinativo do MP de Contas do Paran\u00e1 (MPC-PR), a Primeira C\u00e2mara do Tribunal de Contas do Paran\u00e1 (TCE-PR) expediu determina\u00e7\u00e3o \u00e0 ParanaPrevid\u00eancia para que, no prazo de 30 dias, adote medidas para o ressarcimento de valores indevidamente pagos a maior para servidora aposentada no cargo de Professora do Ensino Superior. Tal decis\u00e3o foi [&hellip;]","og_url":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/","og_site_name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","article_publisher":"https:\/\/www.facebook.com\/mpc.pr","article_published_time":"2021-03-10T16:07:23+00:00","article_modified_time":"2021-03-24T16:45:23+00:00","og_image":[{"width":640,"height":500,"url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg","type":"image\/jpeg"}],"author":"mpcontaspr","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mpcontaspr","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/#article","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/"},"author":{"name":"mpcontaspr","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/person\/2d83cb8980538d0ec174e8a6284f5e11"},"headline":"TCE-PR determina que ParanaPrevid\u00eancia adote medidas para ressarcir valores pagos indevidamente","datePublished":"2021-03-10T16:07:23+00:00","dateModified":"2021-03-24T16:45:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/"},"wordCount":837,"commentCount":0,"publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg","keywords":["Aposentadoria","Benef\u00edcio","Ensino Superior","MPC-PR","ParanaPrevid\u00eancia","Primeira C\u00e2mara","Professora","Revis\u00e3o de Proventos","TCE-PR","Uniformidade de Jurisprud\u00eancia"],"articleSection":["Todas as not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/","url":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/","name":"TCE-PR determina que ParanaPrevid\u00eancia adote medidas para ressarcir valores pagos indevidamente - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/#primaryimage"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg","datePublished":"2021-03-10T16:07:23+00:00","dateModified":"2021-03-24T16:45:23+00:00","breadcrumb":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/#primaryimage","url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg","contentUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg","width":640,"height":500,"caption":"Sede do servi\u00e7o social aut\u00f4nomo Paranaprevid\u00eancia, em Curitiba. Foto: Wagner Ara\u00fajo\/Divulga\u00e7\u00e3o TCE-PR."},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-que-paranaprevidencia-adote-medidas-para-ressarcir-valores-pagos-indevidamente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.mpc.pr.gov.br\/"},{"@type":"ListItem","position":2,"name":"TCE-PR determina que ParanaPrevid\u00eancia adote medidas para ressarcir valores pagos indevidamente"}]},{"@type":"WebSite","@id":"https:\/\/www.mpc.pr.gov.br\/#website","url":"https:\/\/www.mpc.pr.gov.br\/","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","description":"","publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpc.pr.gov.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.mpc.pr.gov.br\/#organization","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","url":"https:\/\/www.mpc.pr.gov.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","contentUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","width":243,"height":73,"caption":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mpc.pr","https:\/\/www.instagram.com\/mpc.pr\/?hl=pt-br","https:\/\/www.youtube.com\/channel\/UCHri5oEM8DV0ztX57E0sBSw"]},{"@type":"Person","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/person\/2d83cb8980538d0ec174e8a6284f5e11","name":"mpcontaspr","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g","caption":"mpcontaspr"},"sameAs":["http:\/\/www.mpc.pr.gov.br"]}]}},"rttpg_featured_image_url":{"full":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg",640,500,false],"landscape":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg",640,500,false],"portraits":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg",640,500,false],"thumbnail":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia-150x150.jpg",150,150,true],"medium":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia-300x234.jpg",300,234,true],"large":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg",640,500,false],"1536x1536":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg",640,500,false],"2048x2048":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg",640,500,false],"ocean-thumb-m":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg",600,469,false],"ocean-thumb-ml":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg",576,450,false],"ocean-thumb-l":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/03\/ParanaPrevidencia.jpg",640,500,false]},"rttpg_author":{"display_name":"mpcontaspr","author_link":"https:\/\/www.mpc.pr.gov.br\/index.php\/author\/mpcontaspr\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/category\/todas-as-noticias\/\" rel=\"category tag\">Todas as not\u00edcias<\/a>","rttpg_excerpt":"Acompanhando o opinativo do MP de Contas do Paran\u00e1 (MPC-PR), a Primeira C\u00e2mara do Tribunal de Contas do Paran\u00e1 (TCE-PR) expediu determina\u00e7\u00e3o \u00e0 ParanaPrevid\u00eancia para que, no prazo de 30 dias, adote medidas para o ressarcimento de valores indevidamente pagos a maior para servidora aposentada no cargo de Professora do Ensino Superior. Tal decis\u00e3o foi&hellip;","_links":{"self":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/11569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=11569"}],"version-history":[{"count":5,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/11569\/revisions"}],"predecessor-version":[{"id":11581,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/11569\/revisions\/11581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media\/11566"}],"wp:attachment":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=11569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/categories?post=11569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/tags?post=11569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}