{"id":12104,"date":"2021-05-17T11:40:16","date_gmt":"2021-05-17T14:40:16","guid":{"rendered":"http:\/\/www.mpc.pr.gov.br\/?p=12104"},"modified":"2021-05-31T10:05:51","modified_gmt":"2021-05-31T13:05:51","slug":"tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia","status":"publish","type":"post","link":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/","title":{"rendered":"TCE-PR determina a aplica\u00e7\u00e3o de multas a Diretora Presidente da Paranagu\u00e1 Previd\u00eancia"},"content":{"rendered":"<figure id=\"attachment_12105\" aria-describedby=\"caption-attachment-12105\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-12105 size-medium\" src=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua-300x225.jpg 300w, https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-12105\" class=\"wp-caption-text\">Vista de Paranagu\u00e1, no Litoral do Estado, o primeiro munic\u00edpio do Paran\u00e1. Foto: Prefeitura de Paranagu\u00e1\/Divulga\u00e7\u00e3o.<\/figcaption><\/figure>\n<p>O Pleno do Tribunal de Contas do Paran\u00e1 (TCE-PR), acolhendo a proposta do MP de Contas do Paran\u00e1 (MPC-PR), emitiu uma medida cautelar \u00e0 Paranagu\u00e1 Previd\u00eancia determinando que a entidade promova o rec\u00e1lculo do benef\u00edcio de aposentadoria concedido a uma servidora ocupante do cargo de Auxiliar Administrativo, com edi\u00e7\u00e3o de novo ato de inativa\u00e7\u00e3o no prazo improrrog\u00e1vel de 15 dias, sob pena de suspens\u00e3o do pagamento dos proventos e responsabiliza\u00e7\u00e3o da gestora da entidade, bem como dos demais respons\u00e1veis pela edi\u00e7\u00e3o do ato irregular, al\u00e9m dos integrantes do Controle Interno municipal.<\/p>\n<p>Na decis\u00e3o, proferia no <a href=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Acordao-867-21.pdf\">Ac\u00f3rd\u00e3o n\u00ba 867\/21<\/a> do Tribunal Pleno, o relator do processo, Conselheiro Artag\u00e3o de Mattos Le\u00e3o, tamb\u00e9m indeferiu o pedido da Paranagu\u00e1 Previd\u00eancia para prorroga\u00e7\u00e3o de prazo para regulariza\u00e7\u00e3o de diverg\u00eancias nos dados informados no SIAP com os documentos apresentados pela entidade, as quais foram apontadas pela Coordenadoria de Atos de Gest\u00e3o (CAGE).<\/p>\n<p>O relator destacou que tem se observado a ocorr\u00eancia de litig\u00e2ncia de m\u00e1-f\u00e9, em raz\u00e3o da conduta reiterada em diversos atos de inativa\u00e7\u00e3o que tamb\u00e9m tem como entidade previdenci\u00e1ria a Paranagu\u00e1 Previd\u00eancia. Nesse sentido, ressalta o relator que restou clara a inten\u00e7\u00e3o protelat\u00f3ria da entidade, que deixou de cumprir as determina\u00e7\u00f5es por cerca de oito meses, agindo de m\u00e1-f\u00e9, em preju\u00edzo do bom andamento processual, atitude esta reprov\u00e1vel e que deve ser coibida. Por esse motivo, o TCE-PR determinou a aplica\u00e7\u00e3o das multas previstas no artigo 87, I, \u201cB\u201d, e IV, \u201cH\u201d, da <a href=\"https:\/\/www1.tce.pr.gov.br\/multimidia\/2005\/12\/pdf\/00084392.pdf\">Lei Complementar n.\u00ba 113\/05<\/a>, em desfavor da Diretora Presidente da entidade.<\/p>\n<p><strong>Instru\u00e7\u00e3o do Processo<\/strong><\/p>\n<p>Tal decis\u00e3o se deu no processo de ato de inativa\u00e7\u00e3o, no qual se analisava a concess\u00e3o de aposentadoria a servidora ocupante do cargo de Auxiliar Administrativo pela Paranagu\u00e1 Previd\u00eancia, com fundamento no artigo 3\u00ba da <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/emendas\/emc\/emc47.htm\">Emenda Constitucional n\u00ba 47\/2005<\/a>.<\/p>\n<p>No decorrer do processo, a Paranagu\u00e1 Previd\u00eancia se manifestou informando que estaria constituindo uma Comiss\u00e3o Interna para dar cumprimento \u00e0 solicita\u00e7\u00e3o da CAGE, motivo pelo qual requereu a suspens\u00e3o do processo pelo prazo n\u00e3o inferior a 90 dias. Por meio do Despacho n\u00ba 1526\/20, o TCE-PR requereu que a entidade comprovasse documentalmente a instala\u00e7\u00e3o da referida comiss\u00e3o, concedendo-se o prazo de 15 dias para isso.<\/p>\n<p>Na sequ\u00eancia a entidade juntou documentos acerca da cria\u00e7\u00e3o da Comiss\u00e3o, mas informou que devido ao surto do Coronav\u00edrus a quantidade de Procuradores dispon\u00edveis na Prefeitura encontra-se reduzida, o que estaria dificultando a an\u00e1lise e julgamento das demandas processuais. Por conta disso, requereu novamente a suspens\u00e3o do processo pelo prazo n\u00e3o inferior a 30 dias.<\/p>\n<p>O Conselheiro Artag\u00e3o de Mattos Le\u00e3o, excepcionalmente, concedeu novo prazo \u00e0 entidade pelo per\u00edodo de 30 dias. Contudo, encerrado o tempo determinado, a entidade previdenci\u00e1ria novamente solicitou prorroga\u00e7\u00e3o do prazo, por mais 15 dias, sob pretexto de que os servidores respons\u00e1veis por atender as demandas recebidas pelo TCE-PR encontram-se afastados em raz\u00e3o de contamina\u00e7\u00e3o do Coronav\u00edrus.<\/p>\n<p>Instado a se manifestar, o MP de Contas, por meio do <a href=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Parecer-167-21.pdf\">Parecer n\u00ba 167\/21<\/a>, considerou que os reiterados pedidos para prorroga\u00e7\u00e3o de prazo requeridos pela Paranagu\u00e1 Previd\u00eancia t\u00eam o intuito notadamente protelat\u00f3rio, que mascaram a sistem\u00e1tica resist\u00eancia em corrigir ao ato de inativa\u00e7\u00e3o aos preceitos do determinado pelo artigo 16 da Lei Complementar Municipal n\u00ba 53\/2006.<\/p>\n<p>O MPC-PR verificou que o fundamento legal do ato de inativa\u00e7\u00e3o em exame, e n\u00e3o o direito \u00e0 aposentadoria da servidora, est\u00e1 em contrariedade com o entendimento fixado pelo Tribunal Pleno, conforme <a href=\"https:\/\/www1.tce.pr.gov.br\/multimidia\/2020\/5\/pdf\/00344758.pdf\">Prejulgado n\u00ba 28<\/a>. Al\u00e9m disso, observou que inexiste possibilidade jur\u00eddica de vincula\u00e7\u00e3o da servidora ao regime estatut\u00e1rio institu\u00eddo pela Lei Municipal n\u00ba 886\/1972, pois, em que pese a aus\u00eancia de submiss\u00e3o \u00e0 pr\u00e9vio concurso p\u00fablico, inexiste nos autos qualquer documento comprobat\u00f3rio de que a servidora tenha efetuado contribui\u00e7\u00f5es previdenci\u00e1rias ao IPE no curso de seu hist\u00f3rico funcional.<\/p>\n<p>Considerando que a interessada s\u00f3 passou a ostentar a qualidade de servidor p\u00fablico em 2006, o que impede a frui\u00e7\u00e3o de aposentadoria com base no artigo 3\u00ba da <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/emendas\/emc\/emc47.htm\">EC n\u00ba 47\/05<\/a>, informou que \u00e9 poss\u00edvel a concess\u00e3o do benef\u00edcio pelas regras da Lei Complementar Municipal n\u00ba 53\/2006, conforme artigos 13 e 16.<\/p>\n<p>O MP de Contas concluiu pela negativa do registro de ato de inativa\u00e7\u00e3o em exame. Contudo, tendo em vista que os pagamentos efetuados \u00e0 servidora ser\u00e3o irrepet\u00edveis, em raz\u00e3o do car\u00e1ter alimentar de que se revestem (o que caracteriza poss\u00edvel irreparabilidade do dano causado ao Fundo de Previd\u00eancia Municipal e, por extens\u00e3o, ao er\u00e1rio e aos mun\u00edcipes), solicitou a imediata determina\u00e7\u00e3o cautelar de emiss\u00e3o de novo ato de inativa\u00e7\u00e3o adequando a fundamenta\u00e7\u00e3o jur\u00eddica e a forma de c\u00e1lculo do benef\u00edcio aos ditames da LC n\u00ba 53\/2006.<\/p>\n<p><strong>Decis\u00e3o<\/strong><\/p>\n<p>Os membros do Tribunal Pleno, acompanharam o voto do relator pelo indeferimento do pedido de prorroga\u00e7\u00e3o de prazo e deferimento da medida cautelar requerida pelo MPC-PR, a fim de determinar a Paranagu\u00e1 Previd\u00eancia o rec\u00e1lculo do benef\u00edcio da servidora. Al\u00e9m disso, tamb\u00e9m foi determinada a aplica\u00e7\u00e3o das multas previstas no artigo 87, I, \u201cB\u201d, e IV, \u201cH\u201d, da <a href=\"https:\/\/www1.tce.pr.gov.br\/multimidia\/2005\/12\/pdf\/00084392.pdf\">Lei Complementar n.\u00ba 113\/05<\/a>, em desfavor da Diretora Presidente da entidade previdenci\u00e1ria.<\/p>\n<p>A decis\u00e3o foi proferida no Ac\u00f3rd\u00e3o n\u00ba 867\/21 e est\u00e1 dispon\u00edvel <a href=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Acordao-867-21.pdf\">aqui<\/a>.<\/p>\n<blockquote><p><span style=\"color: #820007;\"><strong><u>Informa\u00e7\u00e3o para consulta processual<\/u><\/strong><\/span><\/p>\n<table border=\"0\" width=\"629\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td><strong>Processo<\/strong>\u00a0<strong>n\u00ba<\/strong>:<\/td>\n<td>101163\/19<\/td>\n<\/tr>\n<tr>\n<td><strong>Ac\u00f3rd\u00e3o n\u00ba:<\/strong><\/td>\n<td>867\/21 &#8211; Tribunal Pleno<\/td>\n<\/tr>\n<tr>\n<td><strong>Assunto<\/strong>:<\/td>\n<td>Ato de Inativa\u00e7\u00e3o<\/td>\n<\/tr>\n<tr>\n<td><strong>Entidade<\/strong>:<\/td>\n<td>Paranagu\u00e1 Previd\u00eancia<\/td>\n<\/tr>\n<tr>\n<td><strong>Interessados<\/strong>:<\/td>\n<td>Adriana Maia Albini, Marcelo Elias Roque, Marilena Campos Rodrigues, Munic\u00edpio de Paranagu\u00e1, Paranagu\u00e1 Previd\u00eancia, Raul da Gama e Silva Luck<\/td>\n<\/tr>\n<tr>\n<td><strong>Relator<\/strong>:<\/td>\n<td>Conselheiro Artag\u00e3o de Mattos Le\u00e3o<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>O Pleno do Tribunal de Contas do Paran\u00e1 (TCE-PR), acolhendo a proposta do MP de Contas do Paran\u00e1 (MPC-PR), emitiu uma medida cautelar \u00e0 Paranagu\u00e1 Previd\u00eancia determinando que a entidade promova o rec\u00e1lculo do benef\u00edcio de aposentadoria concedido a uma servidora ocupante do cargo de Auxiliar Administrativo, com edi\u00e7\u00e3o de novo ato de inativa\u00e7\u00e3o no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[164,44,13,87,263,138,39,71],"class_list":["post-12104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-todas-as-noticias","tag-ato-de-inativacao","tag-coronavirus","tag-mpc-pr","tag-paranagua","tag-paranagua-previdencia","tag-previdencia","tag-tce-pr","tag-tribunal-pleno","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TCE-PR determina a aplica\u00e7\u00e3o de multas a Diretora Presidente da Paranagu\u00e1 Previd\u00eancia - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TCE-PR determina a aplica\u00e7\u00e3o de multas a Diretora Presidente da Paranagu\u00e1 Previd\u00eancia - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"og:description\" content=\"O Pleno do Tribunal de Contas do Paran\u00e1 (TCE-PR), acolhendo a proposta do MP de Contas do Paran\u00e1 (MPC-PR), emitiu uma medida cautelar \u00e0 Paranagu\u00e1 Previd\u00eancia determinando que a entidade promova o rec\u00e1lculo do benef\u00edcio de aposentadoria concedido a uma servidora ocupante do cargo de Auxiliar Administrativo, com edi\u00e7\u00e3o de novo ato de inativa\u00e7\u00e3o no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mpc.pr\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-17T14:40:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-31T13:05:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mpcontaspr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mpcontaspr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/\"},\"author\":{\"name\":\"mpcontaspr\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/person\\\/2d83cb8980538d0ec174e8a6284f5e11\"},\"headline\":\"TCE-PR determina a aplica\u00e7\u00e3o de multas a Diretora Presidente da Paranagu\u00e1 Previd\u00eancia\",\"datePublished\":\"2021-05-17T14:40:16+00:00\",\"dateModified\":\"2021-05-31T13:05:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/\"},\"wordCount\":1018,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Paranagua.jpg\",\"keywords\":[\"Ato de Inativa\u00e7\u00e3o\",\"Coronav\u00edrus\",\"MPC-PR\",\"Paranagu\u00e1\",\"Paranagu\u00e1 Previd\u00eancia\",\"Previd\u00eancia\",\"TCE-PR\",\"Tribunal Pleno\"],\"articleSection\":[\"Todas as not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/\",\"name\":\"TCE-PR determina a aplica\u00e7\u00e3o de multas a Diretora Presidente da Paranagu\u00e1 Previd\u00eancia - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Paranagua.jpg\",\"datePublished\":\"2021-05-17T14:40:16+00:00\",\"dateModified\":\"2021-05-31T13:05:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Paranagua.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Paranagua.jpg\",\"width\":640,\"height\":480,\"caption\":\"Vista de Paranagu\u00e1, no Litoral do Estado, o primeiro munic\u00edpio do Paran\u00e1. Foto: Prefeitura de Paranagu\u00e1\\\/Divulga\u00e7\u00e3o.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TCE-PR determina a aplica\u00e7\u00e3o de multas a Diretora Presidente da Paranagu\u00e1 Previd\u00eancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"contentUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"width\":243,\"height\":73,\"caption\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mpc.pr\",\"https:\\\/\\\/www.instagram.com\\\/mpc.pr\\\/?hl=pt-br\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHri5oEM8DV0ztX57E0sBSw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/person\\\/2d83cb8980538d0ec174e8a6284f5e11\",\"name\":\"mpcontaspr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g\",\"caption\":\"mpcontaspr\"},\"sameAs\":[\"http:\\\/\\\/www.mpc.pr.gov.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TCE-PR determina a aplica\u00e7\u00e3o de multas a Diretora Presidente da Paranagu\u00e1 Previd\u00eancia - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/","og_locale":"pt_BR","og_type":"article","og_title":"TCE-PR determina a aplica\u00e7\u00e3o de multas a Diretora Presidente da Paranagu\u00e1 Previd\u00eancia - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","og_description":"O Pleno do Tribunal de Contas do Paran\u00e1 (TCE-PR), acolhendo a proposta do MP de Contas do Paran\u00e1 (MPC-PR), emitiu uma medida cautelar \u00e0 Paranagu\u00e1 Previd\u00eancia determinando que a entidade promova o rec\u00e1lculo do benef\u00edcio de aposentadoria concedido a uma servidora ocupante do cargo de Auxiliar Administrativo, com edi\u00e7\u00e3o de novo ato de inativa\u00e7\u00e3o no [&hellip;]","og_url":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/","og_site_name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","article_publisher":"https:\/\/www.facebook.com\/mpc.pr","article_published_time":"2021-05-17T14:40:16+00:00","article_modified_time":"2021-05-31T13:05:51+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg","type":"image\/jpeg"}],"author":"mpcontaspr","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mpcontaspr","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/#article","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/"},"author":{"name":"mpcontaspr","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/person\/2d83cb8980538d0ec174e8a6284f5e11"},"headline":"TCE-PR determina a aplica\u00e7\u00e3o de multas a Diretora Presidente da Paranagu\u00e1 Previd\u00eancia","datePublished":"2021-05-17T14:40:16+00:00","dateModified":"2021-05-31T13:05:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/"},"wordCount":1018,"commentCount":1,"publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg","keywords":["Ato de Inativa\u00e7\u00e3o","Coronav\u00edrus","MPC-PR","Paranagu\u00e1","Paranagu\u00e1 Previd\u00eancia","Previd\u00eancia","TCE-PR","Tribunal Pleno"],"articleSection":["Todas as not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/","url":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/","name":"TCE-PR determina a aplica\u00e7\u00e3o de multas a Diretora Presidente da Paranagu\u00e1 Previd\u00eancia - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/#primaryimage"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg","datePublished":"2021-05-17T14:40:16+00:00","dateModified":"2021-05-31T13:05:51+00:00","breadcrumb":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/#primaryimage","url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg","contentUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg","width":640,"height":480,"caption":"Vista de Paranagu\u00e1, no Litoral do Estado, o primeiro munic\u00edpio do Paran\u00e1. Foto: Prefeitura de Paranagu\u00e1\/Divulga\u00e7\u00e3o."},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tce-pr-determina-a-aplicacao-de-multas-a-diretora-presidente-da-paranagua-previdencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.mpc.pr.gov.br\/"},{"@type":"ListItem","position":2,"name":"TCE-PR determina a aplica\u00e7\u00e3o de multas a Diretora Presidente da Paranagu\u00e1 Previd\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/www.mpc.pr.gov.br\/#website","url":"https:\/\/www.mpc.pr.gov.br\/","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","description":"","publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpc.pr.gov.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.mpc.pr.gov.br\/#organization","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","url":"https:\/\/www.mpc.pr.gov.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","contentUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","width":243,"height":73,"caption":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mpc.pr","https:\/\/www.instagram.com\/mpc.pr\/?hl=pt-br","https:\/\/www.youtube.com\/channel\/UCHri5oEM8DV0ztX57E0sBSw"]},{"@type":"Person","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/person\/2d83cb8980538d0ec174e8a6284f5e11","name":"mpcontaspr","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g","caption":"mpcontaspr"},"sameAs":["http:\/\/www.mpc.pr.gov.br"]}]}},"rttpg_featured_image_url":{"full":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg",640,480,false],"landscape":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg",640,480,false],"portraits":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg",640,480,false],"thumbnail":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua-150x150.jpg",150,150,true],"medium":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua-300x225.jpg",300,225,true],"large":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg",640,480,false],"1536x1536":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg",640,480,false],"2048x2048":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg",640,480,false],"ocean-thumb-m":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg",600,450,false],"ocean-thumb-ml":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg",600,450,false],"ocean-thumb-l":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2021\/05\/Paranagua.jpg",640,480,false]},"rttpg_author":{"display_name":"mpcontaspr","author_link":"https:\/\/www.mpc.pr.gov.br\/index.php\/author\/mpcontaspr\/"},"rttpg_comment":1,"rttpg_category":"<a href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/category\/todas-as-noticias\/\" rel=\"category tag\">Todas as not\u00edcias<\/a>","rttpg_excerpt":"O Pleno do Tribunal de Contas do Paran\u00e1 (TCE-PR), acolhendo a proposta do MP de Contas do Paran\u00e1 (MPC-PR), emitiu uma medida cautelar \u00e0 Paranagu\u00e1 Previd\u00eancia determinando que a entidade promova o rec\u00e1lculo do benef\u00edcio de aposentadoria concedido a uma servidora ocupante do cargo de Auxiliar Administrativo, com edi\u00e7\u00e3o de novo ato de inativa\u00e7\u00e3o no&hellip;","_links":{"self":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/12104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=12104"}],"version-history":[{"count":1,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/12104\/revisions"}],"predecessor-version":[{"id":12109,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/12104\/revisions\/12109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media\/12105"}],"wp:attachment":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=12104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/categories?post=12104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/tags?post=12104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}