{"id":20715,"date":"2024-07-25T10:12:26","date_gmt":"2024-07-25T13:12:26","guid":{"rendered":"https:\/\/www.mpc.pr.gov.br\/?p=20715"},"modified":"2024-08-08T10:06:32","modified_gmt":"2024-08-08T13:06:32","slug":"calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria","status":"publish","type":"post","link":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/","title":{"rendered":"C\u00e1lculo de verbas transit\u00f3rias deve ser proporcional ao tempo de contribui\u00e7\u00e3o, sob pena de negativa de registro da aposentadoria"},"content":{"rendered":"<figure id=\"attachment_20717\" aria-describedby=\"caption-attachment-20717\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-20717\" src=\"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" \/><figcaption id=\"caption-attachment-20717\" class=\"wp-caption-text\">Vis\u00e3o a\u00e9rea do Munic\u00edpio de Cascavel, localizado na regi\u00e3o Oeste do Estado do Paran\u00e1. Conforme censo de 2022, \u00e9 o quinto Munic\u00edpio mais populoso da regi\u00e3o, com cerca de 348.051 habitantes. Foto: divulga\u00e7\u00e3o.<\/figcaption><\/figure>\n<p><span data-contrast=\"auto\">O Tribunal de Contas do Paran\u00e1 (TCE-PR) determinou que o Instituto de Previd\u00eancia dos Servidores P\u00fablicos do Munic\u00edpio de Cascavel (IPMC) realize a corre\u00e7\u00e3o do c\u00e1lculo de aposentadoria de servidor ocupante do cargo de professor do Munic\u00edpio, dentro do prazo de 15 dias, contados a partir da publica\u00e7\u00e3o da decis\u00e3o do <\/span><span data-contrast=\"auto\"><a href=\"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/cascavel-ACO-1803_24-S1C.pdf\">Ac\u00f3rd\u00e3o n\u00ba 1803\/24<\/a>.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Durante a instru\u00e7\u00e3o do processo, verificou-se que houve a incorpora\u00e7\u00e3o de verbas transit\u00f3rias de maneira equivocada, motivo que ensejaria na negativa de registro da aposentadoria do servidor. Contudo, em sess\u00e3o de julgamento da Primeira C\u00e2mara, o Conselheiro Maur\u00edcio Requi\u00e3o de Mello e Silva votou pela convers\u00e3o do julgamento em realiza\u00e7\u00e3o de dilig\u00eancia, para que o IPMC realize a corre\u00e7\u00e3o necess\u00e1ria.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<h4><b><span data-contrast=\"auto\">An\u00e1lise inicial<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/h4>\n<p><span data-contrast=\"auto\">A Coordenadoria de Acompanhamento de Atos de Gest\u00e3o (CAGE), conforme Instru\u00e7\u00e3o n\u00ba 3409\/24, entendeu ser irregular a forma como a entidade previdenci\u00e1ria de Cascavel fez a inclus\u00e3o das verbas de car\u00e1ter transit\u00f3rio nos proventos do servidor, considerando-a em sua integralidade, ao passo que deveriam ser calculadas de maneira proporcional em rela\u00e7\u00e3o ao tempo de contribui\u00e7\u00e3o, conforme Princ\u00edpio da Contributividade.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Em an\u00e1lise ao Sistema de Informa\u00e7\u00f5es de Atos de Pessoal (SIAP), a unidade t\u00e9cnica constatou que n\u00e3o houve valida\u00e7\u00e3o da referida verba, justamente por n\u00e3o ter respeitado a sistem\u00e1tica do c\u00e1lculo.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Na mesma oportunidade, CAGE indicou que o TCE-PR fez o julgamento do Incidente de Inconstitucionalidade n\u00ba 47720\/17, o qual versava sobre poss\u00edvel ilegalidade dos dispositivos da <a href=\"https:\/\/leismunicipais.com.br\/a\/pr\/c\/cascavel\/lei-ordinaria\/2011\/578\/5773\/lei-ordinaria-n-5773-2011-dispoe-sobre-a-definicao-da-remuneracao-de-contribuicao-previdenciaria-do-servidor-publico-municipal-da-administracao-direta-autarquica-ou-fundacional-e-da-camara-municipal-e-da-outras-providencias\">Lei Municipal de Cascavel n\u00ba 5773\/2011<\/a>, especificamente sobre a forma como estava prevista a incorpora\u00e7\u00e3o de verbas transit\u00f3rias aos proventos de aposentadoria. Conforme trecho abaixo da decis\u00e3o contida no<a href=\"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/cascavel-2018_STP_ACO_3555.pdf\"> Ac\u00f3rd\u00e3o n\u00ba 3555\/18<\/a>, o Pleno concluiu que:<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u201cPor outro lado, ainda que se admita que o Munic\u00edpio possa optar, dentro de sua compet\u00eancia legislativa, pela utiliza\u00e7\u00e3o das regras de c\u00e1lculo definidas na lei federal para definir a m\u00e9dia das verbas transit\u00f3rias nas aposentadorias concedidas com base nas regras de transi\u00e7\u00e3o, conforme observou a unidade t\u00e9cnica, o valor obtido dever\u00e1 ser proporcionalizado em rela\u00e7\u00e3o ao tempo de contribui\u00e7\u00e3o, em conformidade com as disposi\u00e7\u00f5es contidas nos \u00a7\u00a7 1\u00ba, 2\u00ba e 3\u00ba11 do art. 40 da Constitui\u00e7\u00e3o, para depois ser somado \u00e0s verbas permanentes informadas na \u00faltima remunera\u00e7\u00e3o. Portanto, <\/span><em>a conclus\u00e3o \u00e9 que<\/em><span data-contrast=\"auto\"><em> a reda\u00e7\u00e3o conferida ao par\u00e1grafo 2\u00ba do art. 5\u00ba da Lei Municipal n\u00b0 5.773\/2011 ofende o princ\u00edpio da contributividade previsto no 40, caput, da Constitui\u00e7\u00e3o e as regras de transi\u00e7\u00e3o contidas nas EC 41\/03 e 47\/05<\/em>, ao estabelecer que, em rela\u00e7\u00e3o \u00e0s aposentadorias concedidas com base nas regras de transi\u00e7\u00e3o, ser\u00e3o incorporadas \u00e0 remunera\u00e7\u00e3o de contribui\u00e7\u00e3o as vantagens concedidas a partir da compet\u00eancia julho de 1994, desconsiderando se houve contribui\u00e7\u00e3o previdenci\u00e1ria antes desta data.\u201d<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:1416,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Logo, pelo ato de inativa\u00e7\u00e3o n\u00e3o estar de acordo com as regras de incorpora\u00e7\u00e3o, a CAGE opinou pela negativa do registro da aposentadoria.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<h4><b><span data-contrast=\"auto\">Contradit\u00f3rio<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/h4>\n<p><span data-contrast=\"auto\">O Instituto de Previd\u00eancia dos Servidores P\u00fablicos do Munic\u00edpio de Cascavel adentrou com a a\u00e7\u00e3o <\/span><span data-contrast=\"auto\">n.\u00ba 0025067-48.2021.8.16.0021<\/span><span data-contrast=\"auto\"> perante o Tribunal de Justi\u00e7a do Paran\u00e1 (TJ-PR) alegando que o TCE-PR n\u00e3o possui compet\u00eancia para declarar a inconstitucionalidade das normas, argumentando ser correta a sistem\u00e1tica do c\u00e1lculo de verbas transit\u00f3rias feitas pelo Munic\u00edpio. Requereu, inclusive, a nulidade dos Ac\u00f3rd\u00e3os n\u00ba 3555\/18, 3267\/19 e 4020\/19, oriundos do processo de Incidente de Constitucionalidade n\u00ba 47720\/17, citado anteriormente.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">No \u00e2mbito do TCE-PR, agora se manifestando no processo de aposentadoria, o Instituto solicitou o sobrestamento dos autos at\u00e9 que fosse proferida decis\u00e3o final no judici\u00e1rio<\/span><span data-contrast=\"auto\">.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<h4><b><span data-contrast=\"auto\">An\u00e1lise conclusiva<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/h4>\n<p><span data-contrast=\"auto\">Em nova manifesta\u00e7\u00e3o, a CAGE informou que n\u00e3o seria poss\u00edvel o sobrestamento, visto que o tema j\u00e1 foi apreciado pelo Poder Judici\u00e1rio quando do julgamento do Mandado de Seguran\u00e7a n\u00b0 0015027-07.2020.8.16.0000, ent\u00e3o impetrado pelo Munic\u00edpio de Cascavel.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Por este motivo, e acompanhando outras decis\u00f5es do Tribunal que negaram a solicita\u00e7\u00e3o de sobrestamento do processo \u2013 devido ao reexame da mat\u00e9ria em outras inst\u00e2ncias -, a unidade t\u00e9cnica manteve seu opinativo pela negativa de registro.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Instado a se manifestar, o Minist\u00e9rio P\u00fablico de Contas do Paran\u00e1 (MPC-PR) acompanhou o entendimento da unidade t\u00e9cnica pela negativa de registro do ato de aposentadoria. Em sua fundamenta\u00e7\u00e3o, mediante o <a href=\"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/cascavel-PAR-136_24-4PC.pdf\">Parecer n\u00ba 136\/24<\/a>, afirmou ser incontroverso que o c\u00e1lculo das verbas transit\u00f3rias incorporadas aos proventos do benefici\u00e1rio n\u00e3o observa a decis\u00e3o proferida pelo TCE-PR no Ac\u00f3rd\u00e3o n\u00ba 3555\/18-STP, o qual declarou incidentalmente a inconstitucionalidade do inciso IV, al\u00edneas \u2018a\u2019, \u2018b\u2019 e \u2018c\u2019 do par\u00e1grafo \u00fanico do artigo 3\u00ba, do \u00a7 2\u00ba do artigo 5\u00ba e do artigo 8\u00ba da Lei Municipal n\u00b0 5.773\/2011.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Opinou, em acr\u00e9scimo, pela emiss\u00e3o de determina\u00e7\u00e3o ao Instituto de Previd\u00eancia para que observe o <a href=\"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Prejulgado-11-tce-pr.pdf\">Prejulgado n\u00ba 11<\/a> e, na sequ\u00eancia, adote as medidas regularizadoras cab\u00edveis no que tange \u00e0 proporcionaliza\u00e7\u00e3o das verbas transit\u00f3rias incorporadas aos proventos do servidor em destaque.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<h4><b><span data-contrast=\"auto\">Decis\u00e3o<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/h4>\n<p><span data-contrast=\"auto\">Nos termos do <a href=\"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/cascavel-ACO-1803_24-S1C.pdf\">Ac\u00f3rd\u00e3o n\u00ba 1803\/24<\/a> da Primeira C\u00e2mara do TCE-PR, o Conselheiro Maur\u00edcio Requi\u00e3o de Mello e Silva verificou<\/span><span data-contrast=\"auto\"> que a verba de car\u00e1ter transit\u00f3rio denominada \u201cM\u00e9dia de Gratifica\u00e7\u00f5es Transit\u00f3rias\u201d foi inclu\u00edda de modo integralizado aos proventos do servidor. Contudo, uma vez que a aposentadoria tenha sido concedida ap\u00f3s a emiss\u00e3o do Ac\u00f3rd\u00e3o 3555\/18-STP, deveria o benef\u00edcio ser proporcionalizado ao tempo de contribui\u00e7\u00e3o.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Entretanto, a fim de n\u00e3o prejudicar o direito do interessado, o Relator entendeu que a negativa de registro seria consideravelmente prejudicial ao servidor aposentado, n\u00e3o sendo poss\u00edvel que este arque com as consequ\u00eancias do equ\u00edvoco do \u00f3rg\u00e3o previdenci\u00e1rio e do Munic\u00edpio. Tal entendimento tem respaldo em decis\u00f5es exaradas pelo TCE-PR em processos similares, em que as inconsist\u00eancias apuradas permitiram a convers\u00e3o do feito em dilig\u00eancia, sem preju\u00edzo de aplica\u00e7\u00e3o de san\u00e7\u00e3o ao gestor respons\u00e1vel.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Por este motivo, os Membros da Primeira C\u00e2mara do TCE-PR votaram pela convers\u00e3o do feito em dilig\u00eancia, para que no prazo de 15 dias, a contar da publica\u00e7\u00e3o do Ac\u00f3rd\u00e3o, tanto o Munic\u00edpio de Cascavel como o Instituto de Previd\u00eancia, retifiquem o ato, sob pena de imediata aplica\u00e7\u00e3o da multa prevista no artigo 87, I, al\u00ednea \u201cb\u201d da Lei Org\u00e2nica do TCE-PR, no caso de descumprimento da decis\u00e3o.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:360}\">\u00a0<\/span><\/p>\n<blockquote><p><span style=\"color: #820007;\"><strong><u>Informa\u00e7\u00e3o para consulta processual<\/u><\/strong><\/span><\/p>\n<table style=\"height: 183px;\" border=\"0\" width=\"478\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td><strong>Processo n\u00ba<\/strong>:<\/td>\n<td>375836\/21<\/td>\n<\/tr>\n<tr>\n<td><strong>Ac\u00f3rd\u00e3o n\u00ba<\/strong>:<\/td>\n<td><span class=\"NormalTextRun SCXW188288879 BCX0\">Ac\u00f3rd\u00e3o\u00a0 n\u00ba 1803\/24 &#8211; Primeira C\u00e2mara<\/span><\/td>\n<\/tr>\n<tr>\n<td><strong>Assunto<\/strong>:<\/td>\n<td>Ato de Inativa\u00e7\u00e3o<\/td>\n<\/tr>\n<tr>\n<td><strong>Entidade<\/strong>:<\/td>\n<td>Instituto de Previd\u00eancia dos Servidores P\u00fablicos de Cascavel<\/td>\n<\/tr>\n<tr>\n<td><strong>Relator<\/strong>:<\/td>\n<td><span class=\"TextRun SCXW72281638 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW72281638 BCX0\"><span class=\"TextRun SCXW49990095 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW49990095 BCX0\">Conselheiro <span class=\"TextRun SCXW254751086 BCX0\" lang=\"PT-BR\" xml:lang=\"PT-BR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW254751086 BCX0\">Maur\u00edcio Requi\u00e3o de Mello e Silva<\/span><\/span><span class=\"EOP SCXW254751086 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:279}\">\u00a0<\/span><\/span><\/span><\/span><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal de Contas do Paran\u00e1 (TCE-PR) determinou que o Instituto de Previd\u00eancia dos Servidores P\u00fablicos do Munic\u00edpio de Cascavel (IPMC) realize a corre\u00e7\u00e3o do c\u00e1lculo de aposentadoria de servidor ocupante do cargo de professor do Munic\u00edpio, dentro do prazo de 15 dias, contados a partir da publica\u00e7\u00e3o da decis\u00e3o do Ac\u00f3rd\u00e3o n\u00ba 1803\/24.\u00a0 Durante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[29,600,237,13,138,149,39],"class_list":["post-20715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-todas-as-noticias","tag-aposentadoria","tag-calculo-de-verbas-transitorias","tag-cascavel","tag-mpc-pr","tag-previdencia","tag-primeira-camara","tag-tce-pr","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00e1lculo de verbas transit\u00f3rias deve ser proporcional ao tempo de contribui\u00e7\u00e3o, sob pena de negativa de registro da aposentadoria - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e1lculo de verbas transit\u00f3rias deve ser proporcional ao tempo de contribui\u00e7\u00e3o, sob pena de negativa de registro da aposentadoria - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"og:description\" content=\"O Tribunal de Contas do Paran\u00e1 (TCE-PR) determinou que o Instituto de Previd\u00eancia dos Servidores P\u00fablicos do Munic\u00edpio de Cascavel (IPMC) realize a corre\u00e7\u00e3o do c\u00e1lculo de aposentadoria de servidor ocupante do cargo de professor do Munic\u00edpio, dentro do prazo de 15 dias, contados a partir da publica\u00e7\u00e3o da decis\u00e3o do Ac\u00f3rd\u00e3o n\u00ba 1803\/24.\u00a0 Durante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mpc.pr\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-25T13:12:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T13:06:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-e1721741321615.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"639\" \/>\n\t<meta property=\"og:image:height\" content=\"639\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mpcontaspr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mpcontaspr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/\"},\"author\":{\"name\":\"mpcontaspr\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/person\\\/2d83cb8980538d0ec174e8a6284f5e11\"},\"headline\":\"C\u00e1lculo de verbas transit\u00f3rias deve ser proporcional ao tempo de contribui\u00e7\u00e3o, sob pena de negativa de registro da aposentadoria\",\"datePublished\":\"2024-07-25T13:12:26+00:00\",\"dateModified\":\"2024-08-08T13:06:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/\"},\"wordCount\":1222,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Cascavel-e1721741321615.jpg\",\"keywords\":[\"Aposentadoria\",\"C\u00e1lculo de verbas transit\u00f3rias\",\"Cascavel\",\"MPC-PR\",\"Previd\u00eancia\",\"Primeira C\u00e2mara\",\"TCE-PR\"],\"articleSection\":[\"Todas as not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/\",\"name\":\"C\u00e1lculo de verbas transit\u00f3rias deve ser proporcional ao tempo de contribui\u00e7\u00e3o, sob pena de negativa de registro da aposentadoria - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Cascavel-e1721741321615.jpg\",\"datePublished\":\"2024-07-25T13:12:26+00:00\",\"dateModified\":\"2024-08-08T13:06:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Cascavel-e1721741321615.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Cascavel-e1721741321615.jpg\",\"width\":639,\"height\":639,\"caption\":\"Vis\u00e3o a\u00e9rea do Munic\u00edpio de Cascavel, localizado na regi\u00e3o Oeste do Estado do Paran\u00e1. Conforme censo de 2022, \u00e9 o quinto Munic\u00edpio mais populoso, com cerca de 348.051 habitantes. Foto: divulga\u00e7\u00e3o.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00e1lculo de verbas transit\u00f3rias deve ser proporcional ao tempo de contribui\u00e7\u00e3o, sob pena de negativa de registro da aposentadoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"contentUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"width\":243,\"height\":73,\"caption\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mpc.pr\",\"https:\\\/\\\/www.instagram.com\\\/mpc.pr\\\/?hl=pt-br\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHri5oEM8DV0ztX57E0sBSw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/person\\\/2d83cb8980538d0ec174e8a6284f5e11\",\"name\":\"mpcontaspr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g\",\"caption\":\"mpcontaspr\"},\"sameAs\":[\"http:\\\/\\\/www.mpc.pr.gov.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e1lculo de verbas transit\u00f3rias deve ser proporcional ao tempo de contribui\u00e7\u00e3o, sob pena de negativa de registro da aposentadoria - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/","og_locale":"pt_BR","og_type":"article","og_title":"C\u00e1lculo de verbas transit\u00f3rias deve ser proporcional ao tempo de contribui\u00e7\u00e3o, sob pena de negativa de registro da aposentadoria - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","og_description":"O Tribunal de Contas do Paran\u00e1 (TCE-PR) determinou que o Instituto de Previd\u00eancia dos Servidores P\u00fablicos do Munic\u00edpio de Cascavel (IPMC) realize a corre\u00e7\u00e3o do c\u00e1lculo de aposentadoria de servidor ocupante do cargo de professor do Munic\u00edpio, dentro do prazo de 15 dias, contados a partir da publica\u00e7\u00e3o da decis\u00e3o do Ac\u00f3rd\u00e3o n\u00ba 1803\/24.\u00a0 Durante [&hellip;]","og_url":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/","og_site_name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","article_publisher":"https:\/\/www.facebook.com\/mpc.pr","article_published_time":"2024-07-25T13:12:26+00:00","article_modified_time":"2024-08-08T13:06:32+00:00","og_image":[{"width":639,"height":639,"url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-e1721741321615.jpg","type":"image\/jpeg"}],"author":"mpcontaspr","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mpcontaspr","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/#article","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/"},"author":{"name":"mpcontaspr","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/person\/2d83cb8980538d0ec174e8a6284f5e11"},"headline":"C\u00e1lculo de verbas transit\u00f3rias deve ser proporcional ao tempo de contribui\u00e7\u00e3o, sob pena de negativa de registro da aposentadoria","datePublished":"2024-07-25T13:12:26+00:00","dateModified":"2024-08-08T13:06:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/"},"wordCount":1222,"commentCount":1,"publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-e1721741321615.jpg","keywords":["Aposentadoria","C\u00e1lculo de verbas transit\u00f3rias","Cascavel","MPC-PR","Previd\u00eancia","Primeira C\u00e2mara","TCE-PR"],"articleSection":["Todas as not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/","url":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/","name":"C\u00e1lculo de verbas transit\u00f3rias deve ser proporcional ao tempo de contribui\u00e7\u00e3o, sob pena de negativa de registro da aposentadoria - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/#primaryimage"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-e1721741321615.jpg","datePublished":"2024-07-25T13:12:26+00:00","dateModified":"2024-08-08T13:06:32+00:00","breadcrumb":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/#primaryimage","url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-e1721741321615.jpg","contentUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-e1721741321615.jpg","width":639,"height":639,"caption":"Vis\u00e3o a\u00e9rea do Munic\u00edpio de Cascavel, localizado na regi\u00e3o Oeste do Estado do Paran\u00e1. Conforme censo de 2022, \u00e9 o quinto Munic\u00edpio mais populoso, com cerca de 348.051 habitantes. Foto: divulga\u00e7\u00e3o."},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/calculo-de-verbas-transitorias-deve-ser-proporcional-ao-tempo-de-contribuicao-sob-pena-de-negativa-de-registro-da-aposentadoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.mpc.pr.gov.br\/"},{"@type":"ListItem","position":2,"name":"C\u00e1lculo de verbas transit\u00f3rias deve ser proporcional ao tempo de contribui\u00e7\u00e3o, sob pena de negativa de registro da aposentadoria"}]},{"@type":"WebSite","@id":"https:\/\/www.mpc.pr.gov.br\/#website","url":"https:\/\/www.mpc.pr.gov.br\/","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","description":"","publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpc.pr.gov.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.mpc.pr.gov.br\/#organization","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","url":"https:\/\/www.mpc.pr.gov.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","contentUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","width":243,"height":73,"caption":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mpc.pr","https:\/\/www.instagram.com\/mpc.pr\/?hl=pt-br","https:\/\/www.youtube.com\/channel\/UCHri5oEM8DV0ztX57E0sBSw"]},{"@type":"Person","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/person\/2d83cb8980538d0ec174e8a6284f5e11","name":"mpcontaspr","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1aef51541db7622e05fd639336c9c9f312c2a618396e2b6ca96846362fc5403f?s=96&d=mm&r=g","caption":"mpcontaspr"},"sameAs":["http:\/\/www.mpc.pr.gov.br"]}]}},"rttpg_featured_image_url":{"full":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-e1721741321615.jpg",639,639,false],"landscape":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-e1721741321615.jpg",639,639,false],"portraits":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-e1721741321615.jpg",639,639,false],"thumbnail":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-150x150.jpg",150,150,true],"medium":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-300x300.jpg",300,300,true],"large":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-1024x1024.jpg",1024,1024,true],"1536x1536":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-e1721741321615.jpg",639,639,false],"2048x2048":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-e1721741321615.jpg",639,639,false],"ocean-thumb-m":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-600x600.jpg",600,600,true],"ocean-thumb-ml":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-800x450.jpg",800,450,true],"ocean-thumb-l":["https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2024\/07\/Cascavel-1200x700.jpg",1200,700,true]},"rttpg_author":{"display_name":"mpcontaspr","author_link":"https:\/\/www.mpc.pr.gov.br\/index.php\/author\/mpcontaspr\/"},"rttpg_comment":2,"rttpg_category":"<a href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/category\/todas-as-noticias\/\" rel=\"category tag\">Todas as not\u00edcias<\/a>","rttpg_excerpt":"O Tribunal de Contas do Paran\u00e1 (TCE-PR) determinou que o Instituto de Previd\u00eancia dos Servidores P\u00fablicos do Munic\u00edpio de Cascavel (IPMC) realize a corre\u00e7\u00e3o do c\u00e1lculo de aposentadoria de servidor ocupante do cargo de professor do Munic\u00edpio, dentro do prazo de 15 dias, contados a partir da publica\u00e7\u00e3o da decis\u00e3o do Ac\u00f3rd\u00e3o n\u00ba 1803\/24.\u00a0 Durante&hellip;","_links":{"self":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/20715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=20715"}],"version-history":[{"count":2,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/20715\/revisions"}],"predecessor-version":[{"id":20954,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/20715\/revisions\/20954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media\/20717"}],"wp:attachment":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=20715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/categories?post=20715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/tags?post=20715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}