{"id":5929,"date":"2018-05-21T14:07:59","date_gmt":"2018-05-21T17:07:59","guid":{"rendered":"http:\/\/www.mpc.pr.gov.br\/?p=5929"},"modified":"2018-05-21T14:07:59","modified_gmt":"2018-05-21T17:07:59","slug":"mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria","status":"publish","type":"post","link":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/","title":{"rendered":"MP de Contas encaminha dossi\u00ea com irregularidades na sa\u00fade para Promotoria de Uni\u00e3o da Vit\u00f3ria"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-5930 size-medium alignleft\" src=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2018\/05\/leaves-374246_960_720-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/>O N\u00facleo de Intelig\u00eancia do MP de Contas do Paran\u00e1 apurou diversas irregularidades\u00a0em Uni\u00e3o da Vit\u00f3ria, no que se refere a contrata\u00e7\u00e3o de m\u00e9dicos plantonistas. As informa\u00e7\u00f5es foram encaminhadas \u00e0 Promotoria de Justi\u00e7a do MP do Estado do Paran\u00e1, que ir\u00e1 cobrar esclarecimentos junto ao munic\u00edpio.<\/p>\n<p>De acordo com o dossi\u00ea elaborado pelo MP de Contas, das 46 vagas de m\u00e9dicos na cidade apenas 10 s\u00e3o ocupadas por servidores efetivos. O restante \u00e9 preenchido por profissionais integrantes de empresas contratadas por meio de procedimentos licitat\u00f3rios. Para o \u00f3rg\u00e3o ministerial\u00a0o que ocorre \u00e9 uma terceiriza\u00e7\u00e3o irregular do servi\u00e7o p\u00fablico, uma vez que tais contrata\u00e7\u00f5es s\u00e3o uma burla \u00e0 obrigatoriedade de realiza\u00e7\u00e3o de concurso p\u00fablico.<\/p>\n<p>No mesmo sentido s\u00e3o as contrata\u00e7\u00f5es por meio de dispensa de licita\u00e7\u00e3o. A const\u00e2ncia desse procedimento demonstra falta de planejamento da Administra\u00e7\u00e3o P\u00fablica e que as dispensas n\u00e3o s\u00e3o utilizadas para a corre\u00e7\u00e3o de problemas urgentes e pontuais, mas sim para substitui\u00e7\u00e3o de m\u00e3o de obra que deveria ser provida por meio do concurso.<\/p>\n<p>H\u00e1 ainda as licita\u00e7\u00f5es nas modalidades de preg\u00e3o presencial e eletr\u00f4nico, nas quais o objeto contratado \u2013 atendimento m\u00e9dico nas Unidades B\u00e1sicas de Sa\u00fade (UBSs) e nas Unidades de Pronto Atendimento (UPAs) \u2013 n\u00e3o \u00e9 um servi\u00e7o comum da \u00e1rea da sa\u00fade, mas sim requer especifica\u00e7\u00f5es e qualifica\u00e7\u00f5es t\u00e9cnicas dos profissionais que ser\u00e3o empregados.<\/p>\n<p>Al\u00e9m disso, h\u00e1 casos de contrata\u00e7\u00e3o de empresas de propriedade de m\u00e9dicos aut\u00f4nomos, indicados como servidores celetistas em situa\u00e7\u00e3o ativa, ou seja, que j\u00e1 prestam servi\u00e7o ao munic\u00edpio, o que fere a moralidade p\u00fablica e os princ\u00edpios de isonomia e impessoalidade na Administra\u00e7\u00e3o P\u00fablica na vis\u00e3o da Procuradoria-Geral do MP de Contas. Muitos desses m\u00e9dicos tamb\u00e9m t\u00eam uma excessiva jornada de trabalho, chegando a mais de 500 horas mensais, o que gera d\u00favida acerca da efetiva presta\u00e7\u00e3o do servi\u00e7o p\u00fablico. Para tal fato \u00e9 necess\u00e1ria uma investiga\u00e7\u00e3o mais minuciosa, pois a eventual n\u00e3o presta\u00e7\u00e3o do servi\u00e7o caracteriza-se como dano ao er\u00e1rio, j\u00e1 que pode ter havido a remunera\u00e7\u00e3o sem a devida contrapresta\u00e7\u00e3o pelas partes beneficiadas.<\/p>\n<p>O MP de Contas tamb\u00e9m protocolou uma Representa\u00e7\u00e3o junto ao Tribunal de Contas do Paran\u00e1 (TCE-PR) para que a institui\u00e7\u00e3o tome as provid\u00eancias cab\u00edveis. A Representa\u00e7\u00e3o pode ser acessada <a href=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2018\/04\/Representa%C3%A7%C3%A3o-M%C3%A9dPla-Uni%C3%A3o-da-Vit%C3%B3ria.pdf\">aqui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O N\u00facleo de Intelig\u00eancia do MP de Contas do Paran\u00e1 apurou diversas irregularidades\u00a0em Uni\u00e3o da Vit\u00f3ria, no que se refere a contrata\u00e7\u00e3o de m\u00e9dicos plantonistas. As informa\u00e7\u00f5es foram encaminhadas \u00e0 Promotoria de Justi\u00e7a do MP do Estado do Paran\u00e1, que ir\u00e1 cobrar esclarecimentos junto ao munic\u00edpio. De acordo com o dossi\u00ea elaborado pelo MP de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":5930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,14],"tags":[],"class_list":["post-5929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-todas-as-noticias","category-ultimas-noticias","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MP de Contas encaminha dossi\u00ea com irregularidades na sa\u00fade para Promotoria de Uni\u00e3o da Vit\u00f3ria - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MP de Contas encaminha dossi\u00ea com irregularidades na sa\u00fade para Promotoria de Uni\u00e3o da Vit\u00f3ria - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"og:description\" content=\"O N\u00facleo de Intelig\u00eancia do MP de Contas do Paran\u00e1 apurou diversas irregularidades\u00a0em Uni\u00e3o da Vit\u00f3ria, no que se refere a contrata\u00e7\u00e3o de m\u00e9dicos plantonistas. As informa\u00e7\u00f5es foram encaminhadas \u00e0 Promotoria de Justi\u00e7a do MP do Estado do Paran\u00e1, que ir\u00e1 cobrar esclarecimentos junto ao munic\u00edpio. De acordo com o dossi\u00ea elaborado pelo MP de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mpc.pr\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-21T17:07:59+00:00\" \/>\n<meta name=\"author\" content=\"giovanna.faria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"giovanna.faria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/\"},\"author\":{\"name\":\"giovanna.faria\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/person\\\/d0c5cf9ebb4d8be833c419f3538cf751\"},\"headline\":\"MP de Contas encaminha dossi\u00ea com irregularidades na sa\u00fade para Promotoria de Uni\u00e3o da Vit\u00f3ria\",\"datePublished\":\"2018-05-21T17:07:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/\"},\"wordCount\":452,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Todas as not\u00edcias\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/\",\"name\":\"MP de Contas encaminha dossi\u00ea com irregularidades na sa\u00fade para Promotoria de Uni\u00e3o da Vit\u00f3ria - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2018-05-21T17:07:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MP de Contas encaminha dossi\u00ea com irregularidades na sa\u00fade para Promotoria de Uni\u00e3o da Vit\u00f3ria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"contentUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"width\":243,\"height\":73,\"caption\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mpc.pr\",\"https:\\\/\\\/www.instagram.com\\\/mpc.pr\\\/?hl=pt-br\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHri5oEM8DV0ztX57E0sBSw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/person\\\/d0c5cf9ebb4d8be833c419f3538cf751\",\"name\":\"giovanna.faria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"giovanna.faria\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MP de Contas encaminha dossi\u00ea com irregularidades na sa\u00fade para Promotoria de Uni\u00e3o da Vit\u00f3ria - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/","og_locale":"pt_BR","og_type":"article","og_title":"MP de Contas encaminha dossi\u00ea com irregularidades na sa\u00fade para Promotoria de Uni\u00e3o da Vit\u00f3ria - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","og_description":"O N\u00facleo de Intelig\u00eancia do MP de Contas do Paran\u00e1 apurou diversas irregularidades\u00a0em Uni\u00e3o da Vit\u00f3ria, no que se refere a contrata\u00e7\u00e3o de m\u00e9dicos plantonistas. As informa\u00e7\u00f5es foram encaminhadas \u00e0 Promotoria de Justi\u00e7a do MP do Estado do Paran\u00e1, que ir\u00e1 cobrar esclarecimentos junto ao munic\u00edpio. De acordo com o dossi\u00ea elaborado pelo MP de [&hellip;]","og_url":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/","og_site_name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","article_publisher":"https:\/\/www.facebook.com\/mpc.pr","article_published_time":"2018-05-21T17:07:59+00:00","author":"giovanna.faria","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"giovanna.faria","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/#article","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/"},"author":{"name":"giovanna.faria","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/person\/d0c5cf9ebb4d8be833c419f3538cf751"},"headline":"MP de Contas encaminha dossi\u00ea com irregularidades na sa\u00fade para Promotoria de Uni\u00e3o da Vit\u00f3ria","datePublished":"2018-05-21T17:07:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/"},"wordCount":452,"commentCount":0,"publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/#primaryimage"},"thumbnailUrl":"","articleSection":["Todas as not\u00edcias","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/","url":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/","name":"MP de Contas encaminha dossi\u00ea com irregularidades na sa\u00fade para Promotoria de Uni\u00e3o da Vit\u00f3ria - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/#primaryimage"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/#primaryimage"},"thumbnailUrl":"","datePublished":"2018-05-21T17:07:59+00:00","breadcrumb":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/mp-de-contas-encaminha-dossie-com-irregularidades-na-saude-para-promotoria-de-uniao-da-vitoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.mpc.pr.gov.br\/"},{"@type":"ListItem","position":2,"name":"MP de Contas encaminha dossi\u00ea com irregularidades na sa\u00fade para Promotoria de Uni\u00e3o da Vit\u00f3ria"}]},{"@type":"WebSite","@id":"https:\/\/www.mpc.pr.gov.br\/#website","url":"https:\/\/www.mpc.pr.gov.br\/","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","description":"","publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpc.pr.gov.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.mpc.pr.gov.br\/#organization","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","url":"https:\/\/www.mpc.pr.gov.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","contentUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","width":243,"height":73,"caption":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mpc.pr","https:\/\/www.instagram.com\/mpc.pr\/?hl=pt-br","https:\/\/www.youtube.com\/channel\/UCHri5oEM8DV0ztX57E0sBSw"]},{"@type":"Person","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/person\/d0c5cf9ebb4d8be833c419f3538cf751","name":"giovanna.faria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"giovanna.faria"}}]}},"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"giovanna.faria","author_link":"https:\/\/www.mpc.pr.gov.br\/index.php\/author\/giovanna-faria\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/category\/todas-as-noticias\/\" rel=\"category tag\">Todas as not\u00edcias<\/a> <a href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/category\/ultimas-noticias\/\" rel=\"category tag\">\u00daltimas not\u00edcias<\/a>","rttpg_excerpt":"O N\u00facleo de Intelig\u00eancia do MP de Contas do Paran\u00e1 apurou diversas irregularidades\u00a0em Uni\u00e3o da Vit\u00f3ria, no que se refere a contrata\u00e7\u00e3o de m\u00e9dicos plantonistas. As informa\u00e7\u00f5es foram encaminhadas \u00e0 Promotoria de Justi\u00e7a do MP do Estado do Paran\u00e1, que ir\u00e1 cobrar esclarecimentos junto ao munic\u00edpio. De acordo com o dossi\u00ea elaborado pelo MP de&hellip;","_links":{"self":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/5929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=5929"}],"version-history":[{"count":0,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/5929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=5929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/categories?post=5929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/tags?post=5929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}