{"id":7154,"date":"2019-05-24T14:15:31","date_gmt":"2019-05-24T17:15:31","guid":{"rendered":"http:\/\/www.mpc.pr.gov.br\/?p=7154"},"modified":"2019-05-24T14:15:31","modified_gmt":"2019-05-24T17:15:31","slug":"curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos","status":"publish","type":"post","link":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/","title":{"rendered":"Curitiba adota recomenda\u00e7\u00f5es do MP de Contas e passa a exigir adequado preenchimento da NF-e em aquisi\u00e7\u00f5es de medicamentos"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-6933\" src=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2019\/03\/NOTA-FISCAL-ELETRONICA-300x193.jpg\" alt=\"\" width=\"300\" height=\"193\" \/>O munic\u00edpio de Curitiba comunicou ao MP de Contas do Paran\u00e1 que atendeu integralmente a Recomenda\u00e7\u00e3o Administrativa n\u00b0 1\/2019, a qual foi expedida pelo \u00f3rg\u00e3o ministerial para todos os munic\u00edpios do Estado. No documento constava a sugest\u00e3o de que os servidores respons\u00e1veis pela aquisi\u00e7\u00e3o e recebimento de medicamentos e produtos farmac\u00eauticos passem a exigir dos fornecedores o adequado preenchimento de campos obrigat\u00f3rios da nota fiscal eletr\u00f4nica (NF-e).<\/p>\n<p>Foi determinado o prazo de 60 dias \u00fateis para que os munic\u00edpios comprovassem a ado\u00e7\u00e3o das medidas recomendadas, as quais determinam que na elabora\u00e7\u00e3o dos editais de licita\u00e7\u00e3o esteja prevista a obrigatoriedade de que, quando da entrega dos bens adquiridos, o fornecedor comprove, mediante apresenta\u00e7\u00e3o do respectivo arquivo XML, o preenchimento dos campos do Grupo I80 e K das NF-e.<\/p>\n<p>De acordo com os documentos encaminhados pela Procuradoria-Geral de Curitiba, foram oficiados sobre o conte\u00fado da Recomenda\u00e7\u00e3o a Secretaria Municipal de Sa\u00fade (SMS), servidores do Almoxarifado Central da SMS e a Coordena\u00e7\u00e3o de Recursos Materiais de assist\u00eancia farmac\u00eautica.<\/p>\n<p>Al\u00e9m disso, as Recomenda\u00e7\u00f5es tamb\u00e9m foram inclu\u00eddas no texto do Edital de Embasamento utilizado em aquisi\u00e7\u00f5es de medicamentos e nos editais publicados no sistema e-compras, por meio de um comunicado aos fornecedores.<\/p>\n<p>Tais medidas visam a aumentar o cumprimento das obriga\u00e7\u00f5es tribut\u00e1rias acess\u00f3rias, dentre as quais a Lei Estadual n\u00b0 11.580\/1996, que fixa que \u00e9 dever do fornecedor preencher adequadamente os documentos fiscais, sob pena de aplica\u00e7\u00e3o de multa pelo Fisco.<\/p>\n<p>Ademais, a ado\u00e7\u00e3o das recomenda\u00e7\u00f5es facilita a fiscaliza\u00e7\u00e3o promovida pela Inspetoria Geral de Fiscaliza\u00e7\u00e3o da Receita Estadual e, ainda, pode servir como mecanismo de controle dos pr\u00f3prios munic\u00edpios, que poder\u00e3o confrontar os lotes recebidos com a data informada no documento fiscal, verificando se a validade \u00e9 compat\u00edvel com a perspectiva de utiliza\u00e7\u00e3o.<\/p>\n<p>A Recomenda\u00e7\u00e3o Administrativa n\u00b0 1\/2019 pode ser acessada <a href=\"http:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2019\/03\/Recomenda%C3%A7%C3%A3o-administrativa-01-2019.pdf\">aqui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O munic\u00edpio de Curitiba comunicou ao MP de Contas do Paran\u00e1 que atendeu integralmente a Recomenda\u00e7\u00e3o Administrativa n\u00b0 1\/2019, a qual foi expedida pelo \u00f3rg\u00e3o ministerial para todos os munic\u00edpios do Estado. No documento constava a sugest\u00e3o de que os servidores respons\u00e1veis pela aquisi\u00e7\u00e3o e recebimento de medicamentos e produtos farmac\u00eauticos passem a exigir dos [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":6933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,14],"tags":[],"class_list":["post-7154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-todas-as-noticias","category-ultimas-noticias","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Curitiba adota recomenda\u00e7\u00f5es do MP de Contas e passa a exigir adequado preenchimento da NF-e em aquisi\u00e7\u00f5es de medicamentos - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curitiba adota recomenda\u00e7\u00f5es do MP de Contas e passa a exigir adequado preenchimento da NF-e em aquisi\u00e7\u00f5es de medicamentos - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"og:description\" content=\"O munic\u00edpio de Curitiba comunicou ao MP de Contas do Paran\u00e1 que atendeu integralmente a Recomenda\u00e7\u00e3o Administrativa n\u00b0 1\/2019, a qual foi expedida pelo \u00f3rg\u00e3o ministerial para todos os munic\u00edpios do Estado. No documento constava a sugest\u00e3o de que os servidores respons\u00e1veis pela aquisi\u00e7\u00e3o e recebimento de medicamentos e produtos farmac\u00eauticos passem a exigir dos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/\" \/>\n<meta property=\"og:site_name\" content=\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mpc.pr\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-24T17:15:31+00:00\" \/>\n<meta name=\"author\" content=\"giovanna.faria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"giovanna.faria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/\"},\"author\":{\"name\":\"giovanna.faria\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/person\\\/d0c5cf9ebb4d8be833c419f3538cf751\"},\"headline\":\"Curitiba adota recomenda\u00e7\u00f5es do MP de Contas e passa a exigir adequado preenchimento da NF-e em aquisi\u00e7\u00f5es de medicamentos\",\"datePublished\":\"2019-05-24T17:15:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/\"},\"wordCount\":352,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Todas as not\u00edcias\",\"\u00daltimas not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/\",\"name\":\"Curitiba adota recomenda\u00e7\u00f5es do MP de Contas e passa a exigir adequado preenchimento da NF-e em aquisi\u00e7\u00f5es de medicamentos - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2019-05-24T17:15:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curitiba adota recomenda\u00e7\u00f5es do MP de Contas e passa a exigir adequado preenchimento da NF-e em aquisi\u00e7\u00f5es de medicamentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"contentUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"width\":243,\"height\":73,\"caption\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mpc.pr\",\"https:\\\/\\\/www.instagram.com\\\/mpc.pr\\\/?hl=pt-br\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHri5oEM8DV0ztX57E0sBSw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/person\\\/d0c5cf9ebb4d8be833c419f3538cf751\",\"name\":\"giovanna.faria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"giovanna.faria\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curitiba adota recomenda\u00e7\u00f5es do MP de Contas e passa a exigir adequado preenchimento da NF-e em aquisi\u00e7\u00f5es de medicamentos - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/","og_locale":"pt_BR","og_type":"article","og_title":"Curitiba adota recomenda\u00e7\u00f5es do MP de Contas e passa a exigir adequado preenchimento da NF-e em aquisi\u00e7\u00f5es de medicamentos - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","og_description":"O munic\u00edpio de Curitiba comunicou ao MP de Contas do Paran\u00e1 que atendeu integralmente a Recomenda\u00e7\u00e3o Administrativa n\u00b0 1\/2019, a qual foi expedida pelo \u00f3rg\u00e3o ministerial para todos os munic\u00edpios do Estado. No documento constava a sugest\u00e3o de que os servidores respons\u00e1veis pela aquisi\u00e7\u00e3o e recebimento de medicamentos e produtos farmac\u00eauticos passem a exigir dos [&hellip;]","og_url":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/","og_site_name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","article_publisher":"https:\/\/www.facebook.com\/mpc.pr","article_published_time":"2019-05-24T17:15:31+00:00","author":"giovanna.faria","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"giovanna.faria","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/#article","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/"},"author":{"name":"giovanna.faria","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/person\/d0c5cf9ebb4d8be833c419f3538cf751"},"headline":"Curitiba adota recomenda\u00e7\u00f5es do MP de Contas e passa a exigir adequado preenchimento da NF-e em aquisi\u00e7\u00f5es de medicamentos","datePublished":"2019-05-24T17:15:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/"},"wordCount":352,"commentCount":0,"publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/#primaryimage"},"thumbnailUrl":"","articleSection":["Todas as not\u00edcias","\u00daltimas not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/","url":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/","name":"Curitiba adota recomenda\u00e7\u00f5es do MP de Contas e passa a exigir adequado preenchimento da NF-e em aquisi\u00e7\u00f5es de medicamentos - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/#primaryimage"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/#primaryimage"},"thumbnailUrl":"","datePublished":"2019-05-24T17:15:31+00:00","breadcrumb":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/curitiba-adota-recomendacoes-do-mp-de-contas-e-passa-a-exigir-adequado-preenchimento-da-nf-e-em-aquisicoes-de-medicamentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.mpc.pr.gov.br\/"},{"@type":"ListItem","position":2,"name":"Curitiba adota recomenda\u00e7\u00f5es do MP de Contas e passa a exigir adequado preenchimento da NF-e em aquisi\u00e7\u00f5es de medicamentos"}]},{"@type":"WebSite","@id":"https:\/\/www.mpc.pr.gov.br\/#website","url":"https:\/\/www.mpc.pr.gov.br\/","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","description":"","publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpc.pr.gov.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.mpc.pr.gov.br\/#organization","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","url":"https:\/\/www.mpc.pr.gov.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","contentUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","width":243,"height":73,"caption":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mpc.pr","https:\/\/www.instagram.com\/mpc.pr\/?hl=pt-br","https:\/\/www.youtube.com\/channel\/UCHri5oEM8DV0ztX57E0sBSw"]},{"@type":"Person","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/person\/d0c5cf9ebb4d8be833c419f3538cf751","name":"giovanna.faria","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"giovanna.faria"}}]}},"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"giovanna.faria","author_link":"https:\/\/www.mpc.pr.gov.br\/index.php\/author\/giovanna-faria\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/category\/todas-as-noticias\/\" rel=\"category tag\">Todas as not\u00edcias<\/a> <a href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/category\/ultimas-noticias\/\" rel=\"category tag\">\u00daltimas not\u00edcias<\/a>","rttpg_excerpt":"O munic\u00edpio de Curitiba comunicou ao MP de Contas do Paran\u00e1 que atendeu integralmente a Recomenda\u00e7\u00e3o Administrativa n\u00b0 1\/2019, a qual foi expedida pelo \u00f3rg\u00e3o ministerial para todos os munic\u00edpios do Estado. No documento constava a sugest\u00e3o de que os servidores respons\u00e1veis pela aquisi\u00e7\u00e3o e recebimento de medicamentos e produtos farmac\u00eauticos passem a exigir dos&hellip;","_links":{"self":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/7154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/comments?post=7154"}],"version-history":[{"count":0,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts\/7154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/media?parent=7154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/categories?post=7154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/tags?post=7154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}