{"id":978,"count":1,"description":"","link":"https:\/\/www.mpc.pr.gov.br\/index.php\/tag\/estabilidade\/","name":"Estabilidade","slug":"estabilidade","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Estabilidade - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpc.pr.gov.br\/index.php\/tag\/estabilidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Estabilidade - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpc.pr.gov.br\/index.php\/tag\/estabilidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tag\\\/estabilidade\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tag\\\/estabilidade\\\/\",\"name\":\"Arquivos Estabilidade - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tag\\\/estabilidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/index.php\\\/tag\\\/estabilidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estabilidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#website\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#organization\",\"name\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"contentUrl\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png\",\"width\":243,\"height\":73,\"caption\":\"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpc.pr.gov.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mpc.pr\",\"https:\\\/\\\/www.instagram.com\\\/mpc.pr\\\/?hl=pt-br\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHri5oEM8DV0ztX57E0sBSw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Estabilidade - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpc.pr.gov.br\/index.php\/tag\/estabilidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Estabilidade - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","og_url":"https:\/\/www.mpc.pr.gov.br\/index.php\/tag\/estabilidade\/","og_site_name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tag\/estabilidade\/","url":"https:\/\/www.mpc.pr.gov.br\/index.php\/tag\/estabilidade\/","name":"Arquivos Estabilidade - Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","isPartOf":{"@id":"https:\/\/www.mpc.pr.gov.br\/#website"},"breadcrumb":{"@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tag\/estabilidade\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpc.pr.gov.br\/index.php\/tag\/estabilidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.mpc.pr.gov.br\/"},{"@type":"ListItem","position":2,"name":"Estabilidade"}]},{"@type":"WebSite","@id":"https:\/\/www.mpc.pr.gov.br\/#website","url":"https:\/\/www.mpc.pr.gov.br\/","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","description":"","publisher":{"@id":"https:\/\/www.mpc.pr.gov.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpc.pr.gov.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.mpc.pr.gov.br\/#organization","name":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1","url":"https:\/\/www.mpc.pr.gov.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","contentUrl":"https:\/\/www.mpc.pr.gov.br\/wp-content\/uploads\/2020\/06\/99423647_1593460364143890_6706793420720963584_n-1-e1591387983167.png","width":243,"height":73,"caption":"Minist\u00e9rio P\u00fablico de Contas do Estado do Paran\u00e1"},"image":{"@id":"https:\/\/www.mpc.pr.gov.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mpc.pr","https:\/\/www.instagram.com\/mpc.pr\/?hl=pt-br","https:\/\/www.youtube.com\/channel\/UCHri5oEM8DV0ztX57E0sBSw"]}]}},"_links":{"self":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/tags\/978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mpc.pr.gov.br\/index.php\/wp-json\/wp\/v2\/posts?tags=978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}